{"id":4117,"date":"2023-03-02T14:15:59","date_gmt":"2023-03-02T13:15:59","guid":{"rendered":"https:\/\/agorastur.es\/blog\/?p=4117"},"modified":"2025-03-03T15:09:22","modified_gmt":"2025-03-03T14:09:22","slug":"seminarios-de-marzo-2023","status":"publish","type":"post","link":"https:\/\/agorastur.es\/blog\/seminarios-de-marzo-2023\/","title":{"rendered":"Seminarios de Marzo 2023"},"content":{"rendered":"\n<p>Sabemos que el mes de Marzo puede ser un poco ca\u00f3tico, ya que estamos en pleno cambio de estaci\u00f3n y parece que nunca sabemos qu\u00e9 clima nos va a tocar. Pero no os preocup\u00e9is, en \u00c1gorastur os traemos los seminarios del mes de Marzo para que adaptar vuestro calendario no sea un problema.<\/p>\n\n\n\n<p>\u00bfAlguna vez has sentido que tus conocimientos de inform\u00e1tica no son suficientes? En nuestro seminario de Inform\u00e1tica aprender\u00e1s todo lo necesario para manejar mejor tu ordenador.<\/p>\n\n\n\n<p>Ahora hablemos de los seminarios jur\u00eddicos. Desde la Constituci\u00f3n al Estatuto de Econom\u00eda, conoce todo el marco legal que rige la sociedad espa\u00f1ola.<\/p>\n\n\n\n<p>Para aquellos que aman a los animales, tenemos el seminario de veterinaria. En esta ocasi\u00f3n, aprender\u00e1s cuales son los mejores cuidados para los caballos.<\/p>\n\n\n\n<p>\u00bfAlguna vez han estado en una situaci\u00f3n de emergencia y no supiste qu\u00e9 hacer? Nuestra experta en primeros auxilios te ense\u00f1ar\u00e1 todo lo que necesitas saber para salvar vidas.<\/p>\n\n\n\n<p>Estos son solo algunos de los seminarios que ten\u00e9is disponibles en este mes de marzo. Como pod\u00e9is ver a continuaci\u00f3n, tenemos seminarios de todas las ramas formativas. \u00a1Esperamos veros en algunos de ellos!<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"663\" src=\"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2023\/03\/image-1024x663.png\" alt=\"Seminarios \u00c1gorastur de marzo de 2023\" class=\"wp-image-4120\" srcset=\"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2023\/03\/image-1024x663.png 1024w, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2023\/03\/image-300x194.png 300w, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2023\/03\/image-768x497.png 768w, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2023\/03\/image-960x621.png 960w, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2023\/03\/image.png 1309w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Sabemos que el mes de Marzo puede ser un poco ca\u00f3tico, ya que estamos en pleno cambio de estaci\u00f3n y parece que nunca sabemos qu\u00e9 clima nos va a tocar. Pero no os preocup\u00e9is, en \u00c1gorastur os traemos los seminarios del mes de Marzo para que adaptar vuestro calendario no sea un problema. \u00bfAlguna vez [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4119,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[40],"tags":[],"ppma_author":[259],"class_list":{"0":"post-4117","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-seminarios"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Seminarios de Marzo 2023 - blog \u00e1gorAstur Formaci\u00f3n<\/title>\r\n<meta name=\"description\" content=\"Ya tenemos preparados los seminarios de este mes de marzo. \u00a1Entra y ap\u00fantate al que m\u00e1s te guste!\" \/>\r\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\r\n<meta property=\"og:locale\" content=\"es_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Seminarios de Marzo 2023 - blog \u00e1gorAstur Formaci\u00f3n\" \/>\r\n<meta property=\"og:description\" content=\"Ya tenemos preparados los seminarios de este mes de marzo. \u00a1Entra y ap\u00fantate al que m\u00e1s te guste!\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/agorastur.es\/blog\/seminarios-de-marzo-2023\/\" \/>\r\n<meta property=\"og:site_name\" content=\"blog \u00e1gorAstur Formaci\u00f3n\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/agorasturformacion\" \/>\r\n<meta property=\"article:published_time\" content=\"2023-03-02T13:15:59+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2025-03-03T14:09:22+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2023\/03\/Blog800-\u00d7-550-px-1.webp\" \/>\r\n\t<meta property=\"og:image:width\" content=\"800\" \/>\r\n\t<meta property=\"og:image:height\" content=\"550\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\r\n<meta name=\"author\" content=\"\u00e1gorAstur Formaci\u00f3n\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:creator\" content=\"@Agorastur\" \/>\r\n<meta name=\"twitter:site\" content=\"@Agorastur\" \/>\r\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u00e1gorAstur Formaci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/seminarios-de-marzo-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/seminarios-de-marzo-2023\\\/\"},\"author\":{\"name\":\"\u00e1gorAstur Formaci\u00f3n\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#\\\/schema\\\/person\\\/e22add2390185670fd9a54413f42e33e\"},\"headline\":\"Seminarios de Marzo 2023\",\"datePublished\":\"2023-03-02T13:15:59+00:00\",\"dateModified\":\"2025-03-03T14:09:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/seminarios-de-marzo-2023\\\/\"},\"wordCount\":208,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/seminarios-de-marzo-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Blog800-\u00d7-550-px-1.webp\",\"articleSection\":[\"Seminarios\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/seminarios-de-marzo-2023\\\/\",\"url\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/seminarios-de-marzo-2023\\\/\",\"name\":\"Seminarios de Marzo 2023 - blog \u00e1gorAstur Formaci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/seminarios-de-marzo-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/seminarios-de-marzo-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Blog800-\u00d7-550-px-1.webp\",\"datePublished\":\"2023-03-02T13:15:59+00:00\",\"dateModified\":\"2025-03-03T14:09:22+00:00\",\"description\":\"Ya tenemos preparados los seminarios de este mes de marzo. \u00a1Entra y ap\u00fantate al que m\u00e1s te guste!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/seminarios-de-marzo-2023\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/agorastur.es\\\/blog\\\/seminarios-de-marzo-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/seminarios-de-marzo-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Blog800-\u00d7-550-px-1.webp\",\"contentUrl\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Blog800-\u00d7-550-px-1.webp\",\"width\":800,\"height\":550,\"caption\":\"seminarios febrero 2023- \u00c1gorastur\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/seminarios-de-marzo-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u00e1gorAstur\",\"item\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Seminarios\",\"item\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/novedades\\\/seminarios\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Seminarios de Marzo 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/\",\"name\":\"blog \u00e1gorAstur Formaci\u00f3n\",\"description\":\"Formaci\u00f3n en Asturias y Le\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#organization\",\"name\":\"Grupo Agorastur, S.L.\",\"url\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-rrss.png\",\"contentUrl\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-rrss.png\",\"width\":512,\"height\":512,\"caption\":\"Grupo Agorastur, S.L.\"},\"image\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/agorasturformacion\",\"https:\\\/\\\/x.com\\\/Agorastur\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#\\\/schema\\\/person\\\/e22add2390185670fd9a54413f42e33e\",\"name\":\"\u00e1gorAstur Formaci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-favicon-1-96x96.png07751c8812e77018f06c4e5a1412ef3a\",\"url\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-favicon-1-96x96.png\",\"contentUrl\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-favicon-1-96x96.png\",\"caption\":\"\u00e1gorAstur Formaci\u00f3n\"},\"sameAs\":[\"http:\\\/\\\/agorastur.es\"],\"url\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/author\\\/agorastur\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Seminarios de Marzo 2023 - blog \u00e1gorAstur Formaci\u00f3n","description":"Ya tenemos preparados los seminarios de este mes de marzo. \u00a1Entra y ap\u00fantate al que m\u00e1s te guste!","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"es_ES","og_type":"article","og_title":"Seminarios de Marzo 2023 - blog \u00e1gorAstur Formaci\u00f3n","og_description":"Ya tenemos preparados los seminarios de este mes de marzo. \u00a1Entra y ap\u00fantate al que m\u00e1s te guste!","og_url":"https:\/\/agorastur.es\/blog\/seminarios-de-marzo-2023\/","og_site_name":"blog \u00e1gorAstur Formaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/agorasturformacion","article_published_time":"2023-03-02T13:15:59+00:00","article_modified_time":"2025-03-03T14:09:22+00:00","og_image":[{"width":800,"height":550,"url":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2023\/03\/Blog800-\u00d7-550-px-1.webp","type":"image\/webp"}],"author":"\u00e1gorAstur Formaci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@Agorastur","twitter_site":"@Agorastur","twitter_misc":{"Escrito por":"\u00e1gorAstur Formaci\u00f3n","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agorastur.es\/blog\/seminarios-de-marzo-2023\/#article","isPartOf":{"@id":"https:\/\/agorastur.es\/blog\/seminarios-de-marzo-2023\/"},"author":{"name":"\u00e1gorAstur Formaci\u00f3n","@id":"https:\/\/agorastur.es\/blog\/#\/schema\/person\/e22add2390185670fd9a54413f42e33e"},"headline":"Seminarios de Marzo 2023","datePublished":"2023-03-02T13:15:59+00:00","dateModified":"2025-03-03T14:09:22+00:00","mainEntityOfPage":{"@id":"https:\/\/agorastur.es\/blog\/seminarios-de-marzo-2023\/"},"wordCount":208,"commentCount":2,"publisher":{"@id":"https:\/\/agorastur.es\/blog\/#organization"},"image":{"@id":"https:\/\/agorastur.es\/blog\/seminarios-de-marzo-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2023\/03\/Blog800-\u00d7-550-px-1.webp","articleSection":["Seminarios"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/agorastur.es\/blog\/seminarios-de-marzo-2023\/","url":"https:\/\/agorastur.es\/blog\/seminarios-de-marzo-2023\/","name":"Seminarios de Marzo 2023 - blog \u00e1gorAstur Formaci\u00f3n","isPartOf":{"@id":"https:\/\/agorastur.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agorastur.es\/blog\/seminarios-de-marzo-2023\/#primaryimage"},"image":{"@id":"https:\/\/agorastur.es\/blog\/seminarios-de-marzo-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2023\/03\/Blog800-\u00d7-550-px-1.webp","datePublished":"2023-03-02T13:15:59+00:00","dateModified":"2025-03-03T14:09:22+00:00","description":"Ya tenemos preparados los seminarios de este mes de marzo. \u00a1Entra y ap\u00fantate al que m\u00e1s te guste!","breadcrumb":{"@id":"https:\/\/agorastur.es\/blog\/seminarios-de-marzo-2023\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agorastur.es\/blog\/seminarios-de-marzo-2023\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agorastur.es\/blog\/seminarios-de-marzo-2023\/#primaryimage","url":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2023\/03\/Blog800-\u00d7-550-px-1.webp","contentUrl":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2023\/03\/Blog800-\u00d7-550-px-1.webp","width":800,"height":550,"caption":"seminarios febrero 2023- \u00c1gorastur"},{"@type":"BreadcrumbList","@id":"https:\/\/agorastur.es\/blog\/seminarios-de-marzo-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u00e1gorAstur","item":"https:\/\/agorastur.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Seminarios","item":"https:\/\/agorastur.es\/blog\/novedades\/seminarios\/"},{"@type":"ListItem","position":3,"name":"Seminarios de Marzo 2023"}]},{"@type":"WebSite","@id":"https:\/\/agorastur.es\/blog\/#website","url":"https:\/\/agorastur.es\/blog\/","name":"blog \u00e1gorAstur Formaci\u00f3n","description":"Formaci\u00f3n en Asturias y Le\u00f3n","publisher":{"@id":"https:\/\/agorastur.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agorastur.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/agorastur.es\/blog\/#organization","name":"Grupo Agorastur, S.L.","url":"https:\/\/agorastur.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agorastur.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/03\/cropped-rrss.png","contentUrl":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/03\/cropped-rrss.png","width":512,"height":512,"caption":"Grupo Agorastur, S.L."},"image":{"@id":"https:\/\/agorastur.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/agorasturformacion","https:\/\/x.com\/Agorastur"]},{"@type":"Person","@id":"https:\/\/agorastur.es\/blog\/#\/schema\/person\/e22add2390185670fd9a54413f42e33e","name":"\u00e1gorAstur Formaci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/03\/cropped-favicon-1-96x96.png07751c8812e77018f06c4e5a1412ef3a","url":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/03\/cropped-favicon-1-96x96.png","contentUrl":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/03\/cropped-favicon-1-96x96.png","caption":"\u00e1gorAstur Formaci\u00f3n"},"sameAs":["http:\/\/agorastur.es"],"url":"https:\/\/agorastur.es\/blog\/author\/agorastur\/"}]}},"jetpack_featured_media_url":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2023\/03\/Blog800-\u00d7-550-px-1.webp","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8kSRz-14p","jetpack-related-posts":[{"id":4285,"url":"https:\/\/agorastur.es\/blog\/seminarios-marzo-2024\/","url_meta":{"origin":4117,"position":0},"title":"Seminarios Marzo 2024","author":"\u00e1gorAstur Formaci\u00f3n","date":"13\/03\/2024","format":false,"excerpt":"\u00a1Bienvenidos una vez m\u00e1s a nuestros seminarios! Este mes, estamos encantados de presentar una selecci\u00f3n diversa de seminarios dise\u00f1ados muy espec\u00edficamente para la adquisici\u00f3n de competencias b\u00e1sicas. Ya sab\u00e9is, pod\u00e9is matricularos ya mismo poni\u00e9ndoos en contacto con vuestro tutor o escribi\u00e9ndonos al correo solicitudes@agorastur.com. \u00a1Os esperamos!","rel":"","context":"En \u00abSeminarios\u00bb","block_context":{"text":"Seminarios","link":"https:\/\/agorastur.es\/blog\/novedades\/seminarios\/"},"img":{"alt_text":"Seminarios Marzo 2024","src":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2024\/03\/Blog800-\u00d7-550-px.png","width":350,"height":200,"srcset":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2024\/03\/Blog800-\u00d7-550-px.png 1x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2024\/03\/Blog800-\u00d7-550-px.png 1.5x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2024\/03\/Blog800-\u00d7-550-px.png 2x"},"classes":[]},{"id":3884,"url":"https:\/\/agorastur.es\/blog\/seminarios-de-marzo-del-2022\/","url_meta":{"origin":4117,"position":1},"title":"Seminarios de marzo del 2022","author":"\u00e1gorAstur Formaci\u00f3n","date":"10\/03\/2022","format":false,"excerpt":"Os dejamos el calendario de seminarios te\u00f3ricos y pr\u00e1cticos que se realizar\u00e1n en \u00e1gorAstur durante el mes de marzo. Qu\u00edmica, Matem\u00e1ticas, Ingl\u00e9s, Veterinaria, Dietas, Manipulador de alimentos...\u00a0 No dudes en apuntarte al que m\u00e1s te interese. Por favor, confirma tu asistencia con tu tutor o al mail:\u00a0solicitudes@agorastur.com \u00a1\u00a1Te esperamos!! \ud83d\ude42","rel":"","context":"En \u00abSeminarios\u00bb","block_context":{"text":"Seminarios","link":"https:\/\/agorastur.es\/blog\/novedades\/seminarios\/"},"img":{"alt_text":"seminarios-marzo-2022-agora","src":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2022\/03\/seminarios-de-marzo-de-2022.webp","width":350,"height":200,"srcset":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2022\/03\/seminarios-de-marzo-de-2022.webp 1x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2022\/03\/seminarios-de-marzo-de-2022.webp 1.5x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2022\/03\/seminarios-de-marzo-de-2022.webp 2x"},"classes":[]},{"id":3686,"url":"https:\/\/agorastur.es\/blog\/seminarios-de-marzo-del-2021\/","url_meta":{"origin":4117,"position":2},"title":"Seminarios de marzo del 2021","author":"\u00e1gorAstur Formaci\u00f3n","date":"02\/03\/2021","format":false,"excerpt":"Damos comienzo el mes de marzo con el calendario de los nuevos seminarios de \u00e1gorAstur Formaci\u00f3n. Todos ellos se llevar\u00e1n a cabo de forma online, excepto los que aparecen en amarillo \u00abManipulador de alimentos\u00bb y \u00abPrimeros Auxilios\u00bb que se impartir\u00e1n los d\u00edas 16 y 22 en las sedes de Gij\u00f3n\u2026","rel":"","context":"En \u00abSeminarios\u00bb","block_context":{"text":"Seminarios","link":"https:\/\/agorastur.es\/blog\/novedades\/seminarios\/"},"img":{"alt_text":"","src":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2021\/03\/seminarios-de-marzo-de-2021-en-agorastur.png","width":350,"height":200,"srcset":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2021\/03\/seminarios-de-marzo-de-2021-en-agorastur.png 1x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2021\/03\/seminarios-de-marzo-de-2021-en-agorastur.png 1.5x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2021\/03\/seminarios-de-marzo-de-2021-en-agorastur.png 2x"},"classes":[]},{"id":4069,"url":"https:\/\/agorastur.es\/blog\/seminarios-de-noviembre-2022\/","url_meta":{"origin":4117,"position":3},"title":"Seminarios de Noviembre 2022","author":"\u00e1gorAstur Formaci\u00f3n","date":"07\/11\/2022","format":false,"excerpt":"Os traemos los seminarios te\u00f3ricos y pr\u00e1cticos correspondientes a este nuevo mes de Noviembre. Derecho, Matem\u00e1ticas e incluso Inform\u00e1tica son s\u00f3lo algunos de las materias que ser\u00e1n impartidas. No dudes en apuntarte al que m\u00e1s te interese. Por favor, confirma tu asistencia con tu tutor o al mail:\u00a0solicitudes@agorastur.com \u00a1\u00a1Te esperamos!!\u00a0","rel":"","context":"En \u00abSeminarios\u00bb","block_context":{"text":"Seminarios","link":"https:\/\/agorastur.es\/blog\/novedades\/seminarios\/"},"img":{"alt_text":"seminarios noviembre 2022","src":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2022\/11\/Blog800-\u00d7-550-px.webp","width":350,"height":200,"srcset":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2022\/11\/Blog800-\u00d7-550-px.webp 1x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2022\/11\/Blog800-\u00d7-550-px.webp 1.5x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2022\/11\/Blog800-\u00d7-550-px.webp 2x"},"classes":[]},{"id":3896,"url":"https:\/\/agorastur.es\/blog\/seminarios-de-mayo-del-2022\/","url_meta":{"origin":4117,"position":4},"title":"Seminarios de mayo del 2022","author":"\u00e1gorAstur Formaci\u00f3n","date":"06\/05\/2022","format":false,"excerpt":"Os dejamos el calendario de seminarios te\u00f3ricos y pr\u00e1cticos que se realizar\u00e1n en \u00e1gorAstur durante el mes de mayo. Primeros auxilios, t\u00e9cnicas de estudio, ingl\u00e9s, qu\u00edmica, inform\u00e1tica, jur\u00eddico, manipulador de alimentos... No dudes en apuntarte al que m\u00e1s te interese. Por favor, confirma tu asistencia con tu tutor o al\u2026","rel":"","context":"En \u00abSeminarios\u00bb","block_context":{"text":"Seminarios","link":"https:\/\/agorastur.es\/blog\/novedades\/seminarios\/"},"img":{"alt_text":"seminarios-mayo-2022","src":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2022\/05\/seminarios-de-marzo-de-2022-1.png","width":350,"height":200,"srcset":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2022\/05\/seminarios-de-marzo-de-2022-1.png 1x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2022\/05\/seminarios-de-marzo-de-2022-1.png 1.5x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2022\/05\/seminarios-de-marzo-de-2022-1.png 2x"},"classes":[]},{"id":4163,"url":"https:\/\/agorastur.es\/blog\/seminarios-de-abril-2023\/","url_meta":{"origin":4117,"position":5},"title":"Seminarios de Abril 2023","author":"\u00e1gorAstur Formaci\u00f3n","date":"31\/03\/2023","format":false,"excerpt":"\u00a1Hola a tod@s! Ya est\u00e1n aqu\u00ed los seminarios correspondientes a este mes de abril. \u00bfTe gustar\u00eda desarrollar tus conocimientos sobre inform\u00e1tica? \ud83d\udcbb \u00bfO tal vez siempre quisiste entender mejor las matem\u00e1ticas? \ud83e\uddee \u00bfQuieres aprender sobre anatom\u00eda o primeros auxilios para estar preparado para cualquier situaci\u00f3n? \ud83e\ude7a\ud83d\ude91 Entonces tenemos algo para\u2026","rel":"","context":"En \u00abSeminarios\u00bb","block_context":{"text":"Seminarios","link":"https:\/\/agorastur.es\/blog\/novedades\/seminarios\/"},"img":{"alt_text":"seminarios abril 2023","src":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2023\/03\/Blog800-\u00d7-550-px.png","width":350,"height":200,"srcset":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2023\/03\/Blog800-\u00d7-550-px.png 1x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2023\/03\/Blog800-\u00d7-550-px.png 1.5x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2023\/03\/Blog800-\u00d7-550-px.png 2x"},"classes":[]}],"authors":[{"term_id":259,"user_id":1,"is_guest":0,"slug":"agorastur","display_name":"\u00e1gorAstur Formaci\u00f3n","avatar_url":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/03\/cropped-favicon-1-96x96.png","1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/posts\/4117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/comments?post=4117"}],"version-history":[{"count":1,"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/posts\/4117\/revisions"}],"predecessor-version":[{"id":4121,"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/posts\/4117\/revisions\/4121"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/media\/4119"}],"wp:attachment":[{"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/media?parent=4117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/categories?post=4117"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/tags?post=4117"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/ppma_author?post=4117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}