{"id":4081,"date":"2022-12-02T11:09:37","date_gmt":"2022-12-02T10:09:37","guid":{"rendered":"https:\/\/agorastur.es\/blog\/?p=4081"},"modified":"2025-03-03T15:09:22","modified_gmt":"2025-03-03T14:09:22","slug":"seminarios-de-diciembre-2022","status":"publish","type":"post","link":"https:\/\/agorastur.es\/blog\/seminarios-de-diciembre-2022\/","title":{"rendered":"Seminarios de Diciembre 2022"},"content":{"rendered":"\n<p>Comenzamos Diciembre y os presentamos los \u00faltimos seminarios te\u00f3ricos y pr\u00e1cticos del a\u00f1o.<\/p>\n\n\n\n<p>En esta ocasi\u00f3n contaremos con seminarios de Matem\u00e1ticas, Inform\u00e1tica, Ingl\u00e9s, Anatom\u00eda&#8230;<\/p>\n\n\n\n<p>No dudes en apuntarte al que te interese. Si est\u00e1s interesado, confirma tu asistencia con tu tutor o escribi\u00e9ndonos al email solicitudes@agorastur.com   <\/p>\n\n\n\n<p>Te esperamos!<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"624\" src=\"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2022\/12\/image-1024x624.png\" alt=\"\" class=\"wp-image-4084\" srcset=\"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2022\/12\/image-1024x624.png 1024w, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2022\/12\/image-300x183.png 300w, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2022\/12\/image-768x468.png 768w, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2022\/12\/image-960x585.png 960w, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2022\/12\/image.png 1353w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Comenzamos Diciembre y os presentamos los \u00faltimos seminarios te\u00f3ricos y pr\u00e1cticos del a\u00f1o. En esta ocasi\u00f3n contaremos con seminarios de Matem\u00e1ticas, Inform\u00e1tica, Ingl\u00e9s, Anatom\u00eda&#8230; No dudes en apuntarte al que te interese. Si est\u00e1s interesado, confirma tu asistencia con tu tutor o escribi\u00e9ndonos al email solicitudes@agorastur.com Te esperamos!<\/p>\n","protected":false},"author":1,"featured_media":4085,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[40],"tags":[],"ppma_author":[259],"class_list":{"0":"post-4081","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-seminarios"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Seminarios de Diciembre 2022 - blog \u00e1gorAstur Formaci\u00f3n<\/title>\r\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\r\n<meta property=\"og:locale\" content=\"es_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Seminarios de Diciembre 2022 - blog \u00e1gorAstur Formaci\u00f3n\" \/>\r\n<meta property=\"og:description\" content=\"Comenzamos Diciembre y os presentamos los \u00faltimos seminarios te\u00f3ricos y pr\u00e1cticos del a\u00f1o. En esta ocasi\u00f3n contaremos con seminarios de Matem\u00e1ticas, Inform\u00e1tica, Ingl\u00e9s, Anatom\u00eda&#8230; No dudes en apuntarte al que te interese. Si est\u00e1s interesado, confirma tu asistencia con tu tutor o escribi\u00e9ndonos al email solicitudes@agorastur.com Te esperamos!\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/agorastur.es\/blog\/seminarios-de-diciembre-2022\/\" \/>\r\n<meta property=\"og:site_name\" content=\"blog \u00e1gorAstur Formaci\u00f3n\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/agorasturformacion\" \/>\r\n<meta property=\"article:published_time\" content=\"2022-12-02T10:09:37+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2025-03-03T14:09:22+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2022\/12\/Seminarios-Diciembre-2022.webp\" \/>\r\n\t<meta property=\"og:image:width\" content=\"800\" \/>\r\n\t<meta property=\"og:image:height\" content=\"550\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\r\n<meta name=\"author\" content=\"\u00e1gorAstur Formaci\u00f3n\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:creator\" content=\"@Agorastur\" \/>\r\n<meta name=\"twitter:site\" content=\"@Agorastur\" \/>\r\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u00e1gorAstur Formaci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/seminarios-de-diciembre-2022\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/seminarios-de-diciembre-2022\\\/\"},\"author\":{\"name\":\"\u00e1gorAstur Formaci\u00f3n\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#\\\/schema\\\/person\\\/e22add2390185670fd9a54413f42e33e\"},\"headline\":\"Seminarios de Diciembre 2022\",\"datePublished\":\"2022-12-02T10:09:37+00:00\",\"dateModified\":\"2025-03-03T14:09:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/seminarios-de-diciembre-2022\\\/\"},\"wordCount\":63,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/seminarios-de-diciembre-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Seminarios-Diciembre-2022.webp\",\"articleSection\":[\"Seminarios\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/seminarios-de-diciembre-2022\\\/\",\"url\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/seminarios-de-diciembre-2022\\\/\",\"name\":\"Seminarios de Diciembre 2022 - blog \u00e1gorAstur Formaci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/seminarios-de-diciembre-2022\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/seminarios-de-diciembre-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Seminarios-Diciembre-2022.webp\",\"datePublished\":\"2022-12-02T10:09:37+00:00\",\"dateModified\":\"2025-03-03T14:09:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/seminarios-de-diciembre-2022\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/agorastur.es\\\/blog\\\/seminarios-de-diciembre-2022\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/seminarios-de-diciembre-2022\\\/#primaryimage\",\"url\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Seminarios-Diciembre-2022.webp\",\"contentUrl\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Seminarios-Diciembre-2022.webp\",\"width\":800,\"height\":550,\"caption\":\"Seminarios Diciembre 2022\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/seminarios-de-diciembre-2022\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u00e1gorAstur\",\"item\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Seminarios\",\"item\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/novedades\\\/seminarios\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Seminarios de Diciembre 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/\",\"name\":\"blog \u00e1gorAstur Formaci\u00f3n\",\"description\":\"Formaci\u00f3n en Asturias y Le\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#organization\",\"name\":\"Grupo Agorastur, S.L.\",\"url\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-rrss.png\",\"contentUrl\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-rrss.png\",\"width\":512,\"height\":512,\"caption\":\"Grupo Agorastur, S.L.\"},\"image\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/agorasturformacion\",\"https:\\\/\\\/x.com\\\/Agorastur\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#\\\/schema\\\/person\\\/e22add2390185670fd9a54413f42e33e\",\"name\":\"\u00e1gorAstur Formaci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-favicon-1-96x96.png07751c8812e77018f06c4e5a1412ef3a\",\"url\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-favicon-1-96x96.png\",\"contentUrl\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-favicon-1-96x96.png\",\"caption\":\"\u00e1gorAstur Formaci\u00f3n\"},\"sameAs\":[\"http:\\\/\\\/agorastur.es\"],\"url\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/author\\\/agorastur\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Seminarios de Diciembre 2022 - blog \u00e1gorAstur Formaci\u00f3n","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"es_ES","og_type":"article","og_title":"Seminarios de Diciembre 2022 - blog \u00e1gorAstur Formaci\u00f3n","og_description":"Comenzamos Diciembre y os presentamos los \u00faltimos seminarios te\u00f3ricos y pr\u00e1cticos del a\u00f1o. En esta ocasi\u00f3n contaremos con seminarios de Matem\u00e1ticas, Inform\u00e1tica, Ingl\u00e9s, Anatom\u00eda&#8230; No dudes en apuntarte al que te interese. Si est\u00e1s interesado, confirma tu asistencia con tu tutor o escribi\u00e9ndonos al email solicitudes@agorastur.com Te esperamos!","og_url":"https:\/\/agorastur.es\/blog\/seminarios-de-diciembre-2022\/","og_site_name":"blog \u00e1gorAstur Formaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/agorasturformacion","article_published_time":"2022-12-02T10:09:37+00:00","article_modified_time":"2025-03-03T14:09:22+00:00","og_image":[{"width":800,"height":550,"url":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2022\/12\/Seminarios-Diciembre-2022.webp","type":"image\/webp"}],"author":"\u00e1gorAstur Formaci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@Agorastur","twitter_site":"@Agorastur","twitter_misc":{"Escrito por":"\u00e1gorAstur Formaci\u00f3n","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agorastur.es\/blog\/seminarios-de-diciembre-2022\/#article","isPartOf":{"@id":"https:\/\/agorastur.es\/blog\/seminarios-de-diciembre-2022\/"},"author":{"name":"\u00e1gorAstur Formaci\u00f3n","@id":"https:\/\/agorastur.es\/blog\/#\/schema\/person\/e22add2390185670fd9a54413f42e33e"},"headline":"Seminarios de Diciembre 2022","datePublished":"2022-12-02T10:09:37+00:00","dateModified":"2025-03-03T14:09:22+00:00","mainEntityOfPage":{"@id":"https:\/\/agorastur.es\/blog\/seminarios-de-diciembre-2022\/"},"wordCount":63,"commentCount":0,"publisher":{"@id":"https:\/\/agorastur.es\/blog\/#organization"},"image":{"@id":"https:\/\/agorastur.es\/blog\/seminarios-de-diciembre-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2022\/12\/Seminarios-Diciembre-2022.webp","articleSection":["Seminarios"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/agorastur.es\/blog\/seminarios-de-diciembre-2022\/","url":"https:\/\/agorastur.es\/blog\/seminarios-de-diciembre-2022\/","name":"Seminarios de Diciembre 2022 - blog \u00e1gorAstur Formaci\u00f3n","isPartOf":{"@id":"https:\/\/agorastur.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agorastur.es\/blog\/seminarios-de-diciembre-2022\/#primaryimage"},"image":{"@id":"https:\/\/agorastur.es\/blog\/seminarios-de-diciembre-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2022\/12\/Seminarios-Diciembre-2022.webp","datePublished":"2022-12-02T10:09:37+00:00","dateModified":"2025-03-03T14:09:22+00:00","breadcrumb":{"@id":"https:\/\/agorastur.es\/blog\/seminarios-de-diciembre-2022\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agorastur.es\/blog\/seminarios-de-diciembre-2022\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agorastur.es\/blog\/seminarios-de-diciembre-2022\/#primaryimage","url":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2022\/12\/Seminarios-Diciembre-2022.webp","contentUrl":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2022\/12\/Seminarios-Diciembre-2022.webp","width":800,"height":550,"caption":"Seminarios Diciembre 2022"},{"@type":"BreadcrumbList","@id":"https:\/\/agorastur.es\/blog\/seminarios-de-diciembre-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u00e1gorAstur","item":"https:\/\/agorastur.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Seminarios","item":"https:\/\/agorastur.es\/blog\/novedades\/seminarios\/"},{"@type":"ListItem","position":3,"name":"Seminarios de Diciembre 2022"}]},{"@type":"WebSite","@id":"https:\/\/agorastur.es\/blog\/#website","url":"https:\/\/agorastur.es\/blog\/","name":"blog \u00e1gorAstur Formaci\u00f3n","description":"Formaci\u00f3n en Asturias y Le\u00f3n","publisher":{"@id":"https:\/\/agorastur.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agorastur.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/agorastur.es\/blog\/#organization","name":"Grupo Agorastur, S.L.","url":"https:\/\/agorastur.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agorastur.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/03\/cropped-rrss.png","contentUrl":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/03\/cropped-rrss.png","width":512,"height":512,"caption":"Grupo Agorastur, S.L."},"image":{"@id":"https:\/\/agorastur.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/agorasturformacion","https:\/\/x.com\/Agorastur"]},{"@type":"Person","@id":"https:\/\/agorastur.es\/blog\/#\/schema\/person\/e22add2390185670fd9a54413f42e33e","name":"\u00e1gorAstur Formaci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/03\/cropped-favicon-1-96x96.png07751c8812e77018f06c4e5a1412ef3a","url":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/03\/cropped-favicon-1-96x96.png","contentUrl":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/03\/cropped-favicon-1-96x96.png","caption":"\u00e1gorAstur Formaci\u00f3n"},"sameAs":["http:\/\/agorastur.es"],"url":"https:\/\/agorastur.es\/blog\/author\/agorastur\/"}]}},"jetpack_featured_media_url":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2022\/12\/Seminarios-Diciembre-2022.webp","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8kSRz-13P","jetpack-related-posts":[{"id":3851,"url":"https:\/\/agorastur.es\/blog\/seminarios-de-diciembre-del-2021\/","url_meta":{"origin":4081,"position":0},"title":"Seminarios de diciembre del 2021","author":"\u00e1gorAstur Formaci\u00f3n","date":"03\/12\/2021","format":false,"excerpt":"Llega el \u00faltimo mes del a\u00f1o cargado de seminarios te\u00f3ricos y pr\u00e1cticos en \u00e1gorAstur Formaci\u00f3n. A continuaci\u00f3n os dejamos el calendario donde podr\u00e1s ver fecha y ciudad en el que se desarrollar\u00e1 cada uno. No dudes en apuntarte al que m\u00e1s te guste. Por favor, confirma tu asistencia con tu\u2026","rel":"","context":"En \u00abSeminarios\u00bb","block_context":{"text":"Seminarios","link":"https:\/\/agorastur.es\/blog\/novedades\/seminarios\/"},"img":{"alt_text":"seminarios-diciembre-2021","src":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2021\/12\/seminarios-diciembre-2021.png","width":350,"height":200,"srcset":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2021\/12\/seminarios-diciembre-2021.png 1x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2021\/12\/seminarios-diciembre-2021.png 1.5x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2021\/12\/seminarios-diciembre-2021.png 2x"},"classes":[]},{"id":4087,"url":"https:\/\/agorastur.es\/blog\/seminarios-enero-2023\/","url_meta":{"origin":4081,"position":1},"title":"Seminarios Enero 2023","author":"\u00e1gorAstur Formaci\u00f3n","date":"04\/01\/2023","format":false,"excerpt":"\u00a1Primeros seminarios de 2023! No dudes en apuntarte al que te interese. Si est\u00e1s interesado, confirma tu asistencia con tu tutor o escribi\u00e9ndonos al email\u00a0solicitudes@agorastur.com \u00a1Te esperamos!","rel":"","context":"En \u00abSeminarios\u00bb","block_context":{"text":"Seminarios","link":"https:\/\/agorastur.es\/blog\/novedades\/seminarios\/"},"img":{"alt_text":"seminarios enero 2023","src":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2023\/01\/Blog800-\u00d7-550-px-1.png","width":350,"height":200,"srcset":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2023\/01\/Blog800-\u00d7-550-px-1.png 1x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2023\/01\/Blog800-\u00d7-550-px-1.png 1.5x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2023\/01\/Blog800-\u00d7-550-px-1.png 2x"},"classes":[]},{"id":14202,"url":"https:\/\/agorastur.es\/blog\/seminarios-de-diciembre-2025\/","url_meta":{"origin":4081,"position":2},"title":"Seminarios de diciembre 2025","author":"\u00e1gorAstur Formaci\u00f3n","date":"02\/12\/2025","format":false,"excerpt":"\ud83c\udf84 Diciembre: tiempo de cerrar el a\u00f1o y preparar nuevos comienzos Diciembre marca el final de un ciclo y abre la puerta a nuevas oportunidades. Es el momento perfecto para hacer balance, reconocer tus logros y dar los \u00faltimos pasos formativos que te preparar\u00e1n para empezar el pr\u00f3ximo a\u00f1o con\u2026","rel":"","context":"En \u00abSeminarios\u00bb","block_context":{"text":"Seminarios","link":"https:\/\/agorastur.es\/blog\/novedades\/seminarios\/"},"img":{"alt_text":"","src":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/12\/seminarios-diciembre-2025.jpg","width":350,"height":200,"srcset":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/12\/seminarios-diciembre-2025.jpg 1x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/12\/seminarios-diciembre-2025.jpg 1.5x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/12\/seminarios-diciembre-2025.jpg 2x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/12\/seminarios-diciembre-2025.jpg 3x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/12\/seminarios-diciembre-2025.jpg 4x"},"classes":[]},{"id":4105,"url":"https:\/\/agorastur.es\/blog\/seminarios-de-febrero-2023\/","url_meta":{"origin":4081,"position":3},"title":"Seminarios de Febrero 2023","author":"\u00e1gorAstur Formaci\u00f3n","date":"01\/02\/2023","format":false,"excerpt":"Os traemos los seminarios correspondientes a este mes de febrero. No dudes en apuntarte al que te interese. Si est\u00e1s interesado, confirma tu asistencia con tu tutor o escribi\u00e9ndonos al email\u00a0solicitudes@agorastur.com \u00a1Te esperamos!","rel":"","context":"En \u00abSeminarios\u00bb","block_context":{"text":"Seminarios","link":"https:\/\/agorastur.es\/blog\/novedades\/seminarios\/"},"img":{"alt_text":"seminarios febrero 2023","src":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2023\/02\/Blog800-\u00d7-550-px-1.webp","width":350,"height":200,"srcset":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2023\/02\/Blog800-\u00d7-550-px-1.webp 1x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2023\/02\/Blog800-\u00d7-550-px-1.webp 1.5x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2023\/02\/Blog800-\u00d7-550-px-1.webp 2x"},"classes":[]},{"id":4258,"url":"https:\/\/agorastur.es\/blog\/seminarios-diciembre-2023\/","url_meta":{"origin":4081,"position":4},"title":"Seminarios de Diciembre 2023","author":"\u00e1gorAstur Formaci\u00f3n","date":"04\/12\/2023","format":false,"excerpt":"Ya nos queda poquito para terminar este a\u00f1o y, como cada mes, os traemos nuevos seminarios. No dud\u00e9is en apuntaros al que m\u00e1s os guste. Reservad ya vuestra plaza hablando con vuestro tutor o escribi\u00e9ndonos al correo solicitudes@agorastur.es. \u00a1Os esperamos!","rel":"","context":"En \u00abSeminarios\u00bb","block_context":{"text":"Seminarios","link":"https:\/\/agorastur.es\/blog\/novedades\/seminarios\/"},"img":{"alt_text":"","src":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2023\/12\/Blog800-\u00d7-550-px-3.webp","width":350,"height":200,"srcset":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2023\/12\/Blog800-\u00d7-550-px-3.webp 1x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2023\/12\/Blog800-\u00d7-550-px-3.webp 1.5x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2023\/12\/Blog800-\u00d7-550-px-3.webp 2x"},"classes":[]},{"id":3939,"url":"https:\/\/agorastur.es\/blog\/seminarios-de-septiembre-del-2022\/","url_meta":{"origin":4081,"position":5},"title":"Seminarios de septiembre del 2022","author":"\u00e1gorAstur Formaci\u00f3n","date":"05\/09\/2022","format":false,"excerpt":"Septiembre, mes de objetivos acad\u00e9micos y de vuelta de los seminarios de \u00e1gorAstur.\u00a0 Te dejamos el calendario con la programaci\u00f3n de este mes.\u00a0 Ap\u00fantate al que m\u00e1s te guste confirmando tu asistencia con tu tutor :) \ud83e\udd73","rel":"","context":"En \u00abSeminarios\u00bb","block_context":{"text":"Seminarios","link":"https:\/\/agorastur.es\/blog\/novedades\/seminarios\/"},"img":{"alt_text":"","src":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2022\/09\/seminarios-septiembre-2022.png","width":350,"height":200,"srcset":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2022\/09\/seminarios-septiembre-2022.png 1x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2022\/09\/seminarios-septiembre-2022.png 1.5x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2022\/09\/seminarios-septiembre-2022.png 2x"},"classes":[]}],"authors":[{"term_id":259,"user_id":1,"is_guest":0,"slug":"agorastur","display_name":"\u00e1gorAstur Formaci\u00f3n","avatar_url":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/03\/cropped-favicon-1-96x96.png","1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/posts\/4081","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/comments?post=4081"}],"version-history":[{"count":2,"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/posts\/4081\/revisions"}],"predecessor-version":[{"id":4086,"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/posts\/4081\/revisions\/4086"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/media\/4085"}],"wp:attachment":[{"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/media?parent=4081"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/categories?post=4081"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/tags?post=4081"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/ppma_author?post=4081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}