{"id":3232,"date":"2020-07-12T19:50:59","date_gmt":"2020-07-12T18:50:59","guid":{"rendered":"https:\/\/agorastur.es\/blog\/?p=3232"},"modified":"2020-07-21T16:07:37","modified_gmt":"2020-07-21T15:07:37","slug":"seminarios-de-julio-de-2020","status":"publish","type":"post","link":"https:\/\/agorastur.es\/blog\/seminarios-de-julio-de-2020\/","title":{"rendered":"Seminarios de julio de 2020"},"content":{"rendered":"\n<p>Teniendo en cuenta el \u00e9xito de los seminarios de inform\u00e1tica realizados durante este periodo de confinamiento sobre Microsoft Word y Excel que Agorastur Formaci\u00f3n ha venido realizando de forma online, tenemos buenas noticias. \u00a1Vuelven durante el resto del mes de julio!\u00a0<\/p>\n<p>Todos los lunes y mi\u00e9rcoles para los alumnos de cualquier formaci\u00f3n de Agorastur, sesi\u00f3n doble, a las 11h con Word b\u00e1sico y a la 13h sesi\u00f3n para los que buscan contenido m\u00e1s avanzado. Los mi\u00e9rcoles seguiremos el mismo patr\u00f3n, pero en este caso sobre Microsoft Excel. Ahh! y como sorpresa, el lunes 20 os traemos un seminario extra, sobre Power-Pivot, este en nuestro canal de Youtube.<\/p>\n<p>Esperemos que os gusten, y sobre todo \u00a1Que aprend\u00e1is mucho!\u00a0<\/p>\n<p>NonStop!<img decoding=\"async\" class=\"emoji\" draggable=\"false\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/11\/svg\/1f525.svg\" alt=\"?\" \/> <img decoding=\"async\" class=\"emoji\" draggable=\"false\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/11\/svg\/1f525.svg\" alt=\"?\" \/>\u00a0<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #0000ff;\"><strong>SEMANA DEL 13 DE JULIO<\/strong><\/span><\/p>\n<p><strong>LUNES 13: \u00a0<\/strong>11-12h Word B\u00e1sico \/ 13-14h Word Avanzado<\/p>\n<p><strong>MIERCOLES 15: <\/strong>11-12h Excel B\u00e1sico \/ 13-14h Excel Avanzado<\/p>\n<p>\u00a0<\/p>\n<p style=\"text-align: center;\"><strong><span style=\"color: #0000ff;\">SEMANA DEL 20 DE JULIO<\/span><\/strong><\/p>\n<p><strong>LUNES 20: <\/strong>11-12h Word B\u00e1sico \/ 13-14h Word Avanzado\u00a0 \/ Seminario EXTRA: Power-Pivot (accesible desde el canal de Youtube)<\/p>\n<p><strong>MIERCOLES 22: <\/strong>11-12h Excel B\u00e1sico \/ 13-14h Excel Avanzado<\/p>\n<p>\u00a0<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #0000ff;\"><strong>SEMANA DEL 27 DE JULIO<\/strong><\/span><\/p>\n<p><strong>LUNES 27: <\/strong>11-12h Word B\u00e1sico \/ 13-14h Word Avanzado<\/p>\n<p><strong>MIERCOLES 29: <\/strong>11-12h Excel B\u00e1sico \/ 13-14h Excel Avanzado<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":3259,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[40],"tags":[],"ppma_author":[259],"class_list":{"0":"post-3232","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-seminarios"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Seminarios de julio de 2020 - blog \u00e1gorAstur Formaci\u00f3n<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/agorastur.es\/blog\/seminarios-de-julio-de-2020\/\" \/>\r\n<meta property=\"og:locale\" content=\"es_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Seminarios de julio de 2020 - blog \u00e1gorAstur Formaci\u00f3n\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/agorastur.es\/blog\/seminarios-de-julio-de-2020\/\" \/>\r\n<meta property=\"og:site_name\" content=\"blog \u00e1gorAstur Formaci\u00f3n\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/agorasturformacion\" \/>\r\n<meta property=\"article:published_time\" content=\"2020-07-12T18:50:59+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2020-07-21T15:07:37+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2020\/07\/webinar-julio-agorastur.png\" \/>\r\n\t<meta property=\"og:image:width\" content=\"800\" \/>\r\n\t<meta property=\"og:image:height\" content=\"550\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\r\n<meta name=\"author\" content=\"\u00e1gorAstur Formaci\u00f3n\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:creator\" content=\"@Agorastur\" \/>\r\n<meta name=\"twitter:site\" content=\"@Agorastur\" \/>\r\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u00e1gorAstur Formaci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/seminarios-de-julio-de-2020\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/seminarios-de-julio-de-2020\\\/\"},\"author\":{\"name\":\"\u00e1gorAstur Formaci\u00f3n\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#\\\/schema\\\/person\\\/e22add2390185670fd9a54413f42e33e\"},\"headline\":\"Seminarios de julio de 2020\",\"datePublished\":\"2020-07-12T18:50:59+00:00\",\"dateModified\":\"2020-07-21T15:07:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/seminarios-de-julio-de-2020\\\/\"},\"wordCount\":213,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/seminarios-de-julio-de-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/webinar-julio-agorastur.png\",\"articleSection\":[\"Seminarios\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/seminarios-de-julio-de-2020\\\/\",\"url\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/seminarios-de-julio-de-2020\\\/\",\"name\":\"Seminarios de julio de 2020 - blog \u00e1gorAstur Formaci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/seminarios-de-julio-de-2020\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/seminarios-de-julio-de-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/webinar-julio-agorastur.png\",\"datePublished\":\"2020-07-12T18:50:59+00:00\",\"dateModified\":\"2020-07-21T15:07:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/seminarios-de-julio-de-2020\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/agorastur.es\\\/blog\\\/seminarios-de-julio-de-2020\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/seminarios-de-julio-de-2020\\\/#primaryimage\",\"url\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/webinar-julio-agorastur.png\",\"contentUrl\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/webinar-julio-agorastur.png\",\"width\":800,\"height\":550,\"caption\":\"webinar-julio-agorastur-formaci\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/seminarios-de-julio-de-2020\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u00e1gorAstur\",\"item\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Seminarios\",\"item\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/novedades\\\/seminarios\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Seminarios de julio de 2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/\",\"name\":\"blog \u00e1gorAstur Formaci\u00f3n\",\"description\":\"Formaci\u00f3n en Asturias y Le\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#organization\",\"name\":\"Grupo Agorastur, S.L.\",\"url\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-rrss.png\",\"contentUrl\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-rrss.png\",\"width\":512,\"height\":512,\"caption\":\"Grupo Agorastur, S.L.\"},\"image\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/agorasturformacion\",\"https:\\\/\\\/x.com\\\/Agorastur\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#\\\/schema\\\/person\\\/e22add2390185670fd9a54413f42e33e\",\"name\":\"\u00e1gorAstur Formaci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-favicon-1-96x96.png07751c8812e77018f06c4e5a1412ef3a\",\"url\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-favicon-1-96x96.png\",\"contentUrl\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-favicon-1-96x96.png\",\"caption\":\"\u00e1gorAstur Formaci\u00f3n\"},\"sameAs\":[\"http:\\\/\\\/agorastur.es\"],\"url\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/author\\\/agorastur\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Seminarios de julio de 2020 - blog \u00e1gorAstur Formaci\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agorastur.es\/blog\/seminarios-de-julio-de-2020\/","og_locale":"es_ES","og_type":"article","og_title":"Seminarios de julio de 2020 - blog \u00e1gorAstur Formaci\u00f3n","og_url":"https:\/\/agorastur.es\/blog\/seminarios-de-julio-de-2020\/","og_site_name":"blog \u00e1gorAstur Formaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/agorasturformacion","article_published_time":"2020-07-12T18:50:59+00:00","article_modified_time":"2020-07-21T15:07:37+00:00","og_image":[{"width":800,"height":550,"url":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2020\/07\/webinar-julio-agorastur.png","type":"image\/png"}],"author":"\u00e1gorAstur Formaci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@Agorastur","twitter_site":"@Agorastur","twitter_misc":{"Escrito por":"\u00e1gorAstur Formaci\u00f3n","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agorastur.es\/blog\/seminarios-de-julio-de-2020\/#article","isPartOf":{"@id":"https:\/\/agorastur.es\/blog\/seminarios-de-julio-de-2020\/"},"author":{"name":"\u00e1gorAstur Formaci\u00f3n","@id":"https:\/\/agorastur.es\/blog\/#\/schema\/person\/e22add2390185670fd9a54413f42e33e"},"headline":"Seminarios de julio de 2020","datePublished":"2020-07-12T18:50:59+00:00","dateModified":"2020-07-21T15:07:37+00:00","mainEntityOfPage":{"@id":"https:\/\/agorastur.es\/blog\/seminarios-de-julio-de-2020\/"},"wordCount":213,"commentCount":0,"publisher":{"@id":"https:\/\/agorastur.es\/blog\/#organization"},"image":{"@id":"https:\/\/agorastur.es\/blog\/seminarios-de-julio-de-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2020\/07\/webinar-julio-agorastur.png","articleSection":["Seminarios"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/agorastur.es\/blog\/seminarios-de-julio-de-2020\/","url":"https:\/\/agorastur.es\/blog\/seminarios-de-julio-de-2020\/","name":"Seminarios de julio de 2020 - blog \u00e1gorAstur Formaci\u00f3n","isPartOf":{"@id":"https:\/\/agorastur.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agorastur.es\/blog\/seminarios-de-julio-de-2020\/#primaryimage"},"image":{"@id":"https:\/\/agorastur.es\/blog\/seminarios-de-julio-de-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2020\/07\/webinar-julio-agorastur.png","datePublished":"2020-07-12T18:50:59+00:00","dateModified":"2020-07-21T15:07:37+00:00","breadcrumb":{"@id":"https:\/\/agorastur.es\/blog\/seminarios-de-julio-de-2020\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agorastur.es\/blog\/seminarios-de-julio-de-2020\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agorastur.es\/blog\/seminarios-de-julio-de-2020\/#primaryimage","url":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2020\/07\/webinar-julio-agorastur.png","contentUrl":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2020\/07\/webinar-julio-agorastur.png","width":800,"height":550,"caption":"webinar-julio-agorastur-formaci\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/agorastur.es\/blog\/seminarios-de-julio-de-2020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u00e1gorAstur","item":"https:\/\/agorastur.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Seminarios","item":"https:\/\/agorastur.es\/blog\/novedades\/seminarios\/"},{"@type":"ListItem","position":3,"name":"Seminarios de julio de 2020"}]},{"@type":"WebSite","@id":"https:\/\/agorastur.es\/blog\/#website","url":"https:\/\/agorastur.es\/blog\/","name":"blog \u00e1gorAstur Formaci\u00f3n","description":"Formaci\u00f3n en Asturias y Le\u00f3n","publisher":{"@id":"https:\/\/agorastur.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agorastur.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/agorastur.es\/blog\/#organization","name":"Grupo Agorastur, S.L.","url":"https:\/\/agorastur.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agorastur.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/03\/cropped-rrss.png","contentUrl":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/03\/cropped-rrss.png","width":512,"height":512,"caption":"Grupo Agorastur, S.L."},"image":{"@id":"https:\/\/agorastur.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/agorasturformacion","https:\/\/x.com\/Agorastur"]},{"@type":"Person","@id":"https:\/\/agorastur.es\/blog\/#\/schema\/person\/e22add2390185670fd9a54413f42e33e","name":"\u00e1gorAstur Formaci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/03\/cropped-favicon-1-96x96.png07751c8812e77018f06c4e5a1412ef3a","url":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/03\/cropped-favicon-1-96x96.png","contentUrl":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/03\/cropped-favicon-1-96x96.png","caption":"\u00e1gorAstur Formaci\u00f3n"},"sameAs":["http:\/\/agorastur.es"],"url":"https:\/\/agorastur.es\/blog\/author\/agorastur\/"}]}},"jetpack_featured_media_url":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2020\/07\/webinar-julio-agorastur.png","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8kSRz-Q8","jetpack-related-posts":[{"id":2585,"url":"https:\/\/agorastur.es\/blog\/seminarios-de-julio-del-2019\/","url_meta":{"origin":3232,"position":0},"title":"Seminarios de julio del 2019","author":"\u00e1gorAstur Formaci\u00f3n","date":"01\/07\/2019","format":false,"excerpt":"Seminarios de julio 2019 en \u00e1gorAstur formaci\u00f3n. Comenzamos julio con la ola de calor, pero en Asturias no llega con tanto \u00edmpetu. Os dejamos el calendario de seminarios previstos para este mes veraniego. El calendario de seminarios de julio en \u00e1gorAstur Formaci\u00f3n es: Seminarios de julio 2019 en Oviedo: Lunes\u2026","rel":"","context":"En \u00abSeminarios\u00bb","block_context":{"text":"Seminarios","link":"https:\/\/agorastur.es\/blog\/novedades\/seminarios\/"},"img":{"alt_text":"","src":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2019\/06\/Seminarios-julio-2019.png","width":350,"height":200,"srcset":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2019\/06\/Seminarios-julio-2019.png 1x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2019\/06\/Seminarios-julio-2019.png 1.5x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2019\/06\/Seminarios-julio-2019.png 2x"},"classes":[]},{"id":2615,"url":"https:\/\/agorastur.es\/blog\/seminarios-de-agosto-del-2019\/","url_meta":{"origin":3232,"position":1},"title":"Seminarios de agosto del 2019","author":"\u00e1gorAstur Formaci\u00f3n","date":"31\/07\/2019","format":false,"excerpt":"Seminarios de agosto 2019 en \u00e1gorAstur formaci\u00f3n. \u00bfEst\u00e1s de vacaciones? Disfr\u00fatalas, en caso contrario, en \u00e1gorAstur formaci\u00f3n seguimos abiertos todo el a\u00f1o, para que t\u00fa puedas tener la mejor preparaci\u00f3n. El calendario de seminarios de agosto en \u00e1gorAstur Formaci\u00f3n es: Seminarios de agosto 2019 en Oviedo: Jueves 1 Viernes 2\u2026","rel":"","context":"En \u00abSeminarios\u00bb","block_context":{"text":"Seminarios","link":"https:\/\/agorastur.es\/blog\/novedades\/seminarios\/"},"img":{"alt_text":"","src":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2019\/07\/classroom-1189988_1280.jpg","width":350,"height":200,"srcset":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2019\/07\/classroom-1189988_1280.jpg 1x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2019\/07\/classroom-1189988_1280.jpg 1.5x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2019\/07\/classroom-1189988_1280.jpg 2x"},"classes":[]},{"id":3057,"url":"https:\/\/agorastur.es\/blog\/webinar-microsoft-excel-tablas-y-tablas-dinamicas\/","url_meta":{"origin":3232,"position":2},"title":"Webinar &#8211; Microsoft Excel. Tablas y Tablas Din\u00e1micas","author":"\u00e1gorAstur Formaci\u00f3n","date":"07\/05\/2020","format":false,"excerpt":"Agorastur Formaci\u00f3n\u00a0organiza de\u00a0manera gratuita\u00a0cursos online (webinar) y seminarios para completar tu formaci\u00f3n. En este caso, te ofrecemos nuestro curso online sobre\u00a0Tablas y Tablas Din\u00e1micas, en el que tratamos la introducci\u00f3n al uso y manejo de tablas y gr\u00e1ficos din\u00e1micos en Microsoft Excel (Office 365). URL del Webinar: https:\/\/www.youtube.com\/watch?v=Z3Wp1gnBdFcDuraci\u00f3n aproximada: 45\u2026","rel":"","context":"En \u00abEducaci\u00f3n\u00bb","block_context":{"text":"Educaci\u00f3n","link":"https:\/\/agorastur.es\/blog\/novedades\/educacion\/"},"img":{"alt_text":"EXCEL-AGORASTUR","src":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2020\/05\/curso-webinar-gratis-microsoft-excel-agorastur-formacion.jpg","width":350,"height":200,"srcset":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2020\/05\/curso-webinar-gratis-microsoft-excel-agorastur-formacion.jpg 1x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2020\/05\/curso-webinar-gratis-microsoft-excel-agorastur-formacion.jpg 1.5x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2020\/05\/curso-webinar-gratis-microsoft-excel-agorastur-formacion.jpg 2x"},"classes":[]},{"id":3063,"url":"https:\/\/agorastur.es\/blog\/webinar-microsoft-excel-funciones-texto\/","url_meta":{"origin":3232,"position":3},"title":"Webinar \u2013 Microsoft Excel. Funciones de Texto","author":"\u00e1gorAstur Formaci\u00f3n","date":"13\/05\/2020","format":false,"excerpt":"Agorastur Formaci\u00f3n\u00a0organiza de\u00a0manera gratuita\u00a0cursos online (webinar) y seminarios para completar tu formaci\u00f3n. En este caso, te ofrecemos nuestro curso online sobre\u00a0Funciones de Texto en Microsoft Excel Office 365. En este webinar se nos adentraremos en el uso de diferentes funciones de texto como IZQUIERDA, DERECHA, EXTRAE, entre otras. Adem\u00e1s trabajamos\u2026","rel":"","context":"En \u00abEducaci\u00f3n\u00bb","block_context":{"text":"Educaci\u00f3n","link":"https:\/\/agorastur.es\/blog\/novedades\/educacion\/"},"img":{"alt_text":"EXCEL-AGORASTUR","src":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2020\/05\/curso-webinar-gratis-microsoft-excel-agorastur-formacion.jpg","width":350,"height":200,"srcset":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2020\/05\/curso-webinar-gratis-microsoft-excel-agorastur-formacion.jpg 1x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2020\/05\/curso-webinar-gratis-microsoft-excel-agorastur-formacion.jpg 1.5x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2020\/05\/curso-webinar-gratis-microsoft-excel-agorastur-formacion.jpg 2x"},"classes":[]},{"id":2089,"url":"https:\/\/agorastur.es\/blog\/seminarios-de-septiembre-del-2018\/","url_meta":{"origin":3232,"position":4},"title":"Seminarios de Septiembre del 2018","author":"\u00e1gorAstur Formaci\u00f3n","date":"31\/08\/2018","format":false,"excerpt":"Seminarios de septiembre 2018 en \u00e1gorAstur formaci\u00f3n. Llega el mes de la vuelta de vacaciones y comienza el curso escolar, \u00bfest\u00e1is listos para planificar vuestra asistencia a los seminarios de \u00e1gorAstur formaci\u00f3n? \u00a1Tenemos novedades, nuestras sedes de Langreo y Avil\u00e9s comienzan a tener seminarios! El calendario de seminarios de septiembre\u2026","rel":"","context":"En \u00abSeminarios\u00bb","block_context":{"text":"Seminarios","link":"https:\/\/agorastur.es\/blog\/novedades\/seminarios\/"},"img":{"alt_text":"","src":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2018\/08\/meeting-469574_1280.jpg","width":350,"height":200,"srcset":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2018\/08\/meeting-469574_1280.jpg 1x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2018\/08\/meeting-469574_1280.jpg 1.5x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2018\/08\/meeting-469574_1280.jpg 2x"},"classes":[]},{"id":3060,"url":"https:\/\/agorastur.es\/blog\/webinar-microsoft-excel-funciones-condicionales\/","url_meta":{"origin":3232,"position":5},"title":"Webinar \u2013 Microsoft Excel. Funciones Condicionales","author":"\u00e1gorAstur Formaci\u00f3n","date":"07\/05\/2020","format":false,"excerpt":"Agorastur Formaci\u00f3n\u00a0organiza de\u00a0manera gratuita\u00a0cursos online (webinar) y seminarios para completar tu formaci\u00f3n. En este caso, te ofrecemos nuestro curso online sobre\u00a0Funciones Condicionales, en el que tratamos las f\u00f3rmulas y funciones matriciales. En este webinar se aborda el uso de las funciones SI, Y, O; SI anidado y la funci\u00f3n SI.CONJUNTO\u2026","rel":"","context":"En \u00abEducaci\u00f3n\u00bb","block_context":{"text":"Educaci\u00f3n","link":"https:\/\/agorastur.es\/blog\/novedades\/educacion\/"},"img":{"alt_text":"EXCEL-AGORASTUR","src":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2020\/05\/curso-webinar-gratis-microsoft-excel-agorastur-formacion.jpg","width":350,"height":200,"srcset":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2020\/05\/curso-webinar-gratis-microsoft-excel-agorastur-formacion.jpg 1x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2020\/05\/curso-webinar-gratis-microsoft-excel-agorastur-formacion.jpg 1.5x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2020\/05\/curso-webinar-gratis-microsoft-excel-agorastur-formacion.jpg 2x"},"classes":[]}],"authors":[{"term_id":259,"user_id":1,"is_guest":0,"slug":"agorastur","display_name":"\u00e1gorAstur Formaci\u00f3n","avatar_url":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/03\/cropped-favicon-1-96x96.png","1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/posts\/3232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/comments?post=3232"}],"version-history":[{"count":23,"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/posts\/3232\/revisions"}],"predecessor-version":[{"id":3298,"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/posts\/3232\/revisions\/3298"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/media\/3259"}],"wp:attachment":[{"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/media?parent=3232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/categories?post=3232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/tags?post=3232"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/ppma_author?post=3232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}