{"id":2502,"date":"2019-04-30T09:00:42","date_gmt":"2019-04-30T08:00:42","guid":{"rendered":"https:\/\/agorastur.es\/blog\/?p=2502"},"modified":"2019-05-29T11:23:01","modified_gmt":"2019-05-29T10:23:01","slug":"plantillas-de-soluciones-del-simulacro-auxiliar-administrativo-del-principado","status":"publish","type":"post","link":"https:\/\/agorastur.es\/blog\/plantillas-de-soluciones-del-simulacro-auxiliar-administrativo-del-principado\/","title":{"rendered":"Plantillas de soluciones del Simulacro Auxiliar Administrativo del Principado de Asturias"},"content":{"rendered":"<p>Todos sabemos que hay un proceso selectivo para la <strong>provisi\u00f3n de 117 plazas del cuerpo de auxiliares administrativos de grupo C<\/strong>, subgrupo C2 en turno libre ordinario y libre reservado a personas con discapacidad, convocado por la resoluci\u00f3n del 23 de julio del 2018.<\/p>\n<p><strong>Hemos hecho un simulacro en nuestros centros de formaci\u00f3n<\/strong> para preparar de la forma m\u00e1s adecuada a nuestros alumnos y dejamos la plantilla de soluciones para todos los que hab\u00e9is participado en este ejercicio:<\/p>\n<p><\/p>\n<p><!--more--><\/p>\n\n\n<table class=\"wp-block-table\"><tbody><tr><td><br><\/td><td>A<\/td><td>B<\/td><td>C<\/td><td>D<\/td><\/tr><tr><td>1<\/td><td>x<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>&#8211;<\/td><\/tr><tr><td>2<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><td>&#8211;<\/td><\/tr><tr><td>3<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><td>&#8211;<\/td><\/tr><tr><td>4<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><td>&#8211;<\/td><\/tr><tr><td>5<\/td><td>x<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>&#8211;<\/td><\/tr><tr><td>6<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>x<\/td><\/tr><tr><td>7<\/td><td>x<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>&#8211;<\/td><\/tr><tr><td>8<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><\/tr><tr><td>9<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><\/tr><tr><td>10<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><\/tr><tr><td>11<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>x<\/td><\/tr><tr><td>12<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><td>&#8211;<\/td><\/tr><tr><td>13<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><td>&#8211;<\/td><\/tr><tr><td>14<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>x<\/td><\/tr><tr><td>15<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><td>&#8211;<\/td><\/tr><tr><td>16<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><\/tr><tr><td>17<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><\/tr><tr><td>18<\/td><td>x<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>&#8211;<\/td><\/tr><tr><td>19<\/td><td>x<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>&#8211;<\/td><\/tr><tr><td>20<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><td>&#8211;<\/td><\/tr><tr><td>21<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><\/tr><tr><td>22<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><td>&#8211;<\/td><\/tr><tr><td>23<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><td>&#8211;<\/td><\/tr><tr><td>24<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><td>&#8211;<\/td><\/tr><tr><td>25<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><\/tr><tr><td>26<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><td>&#8211;<\/td><\/tr><tr><td>27<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><td>&#8211;<\/td><\/tr><tr><td>28<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><\/tr><tr><td>29<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><td>&#8211;<\/td><\/tr><tr><td>30<\/td><td>x<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>&#8211;<\/td><\/tr><tr><td>31<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><\/tr><tr><td>32<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><\/tr><tr><td>33<\/td><td>x<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>&#8211;<\/td><\/tr><tr><td>34<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><\/tr><tr><td>35<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><\/tr><tr><td>36<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>x<\/td><\/tr><tr><td>37<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><\/tr><tr><td>38<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><td>&#8211;<\/td><\/tr><tr><td>39<\/td><td>x<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>&#8211;<\/td><\/tr><tr><td>40<\/td><td>x<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>&#8211;<\/td><\/tr><tr><td>41<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><td>&#8211;<\/td><\/tr><tr><td>42<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>x<\/td><\/tr><tr><td>43<\/td><td>x<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>&#8211;<\/td><\/tr><tr><td>44<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><\/tr><tr><td>45<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><td>&#8211;<\/td><\/tr><tr><td>46<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><td>&#8211;<\/td><\/tr><tr><td>47<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><td>&#8211;<\/td><\/tr><tr><td>48<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><\/tr><tr><td>49<\/td><td>x<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>&#8211;<\/td><\/tr><tr><td>50<\/td><td>x<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>&#8211;<\/td><\/tr><tr><td>51<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><\/tr><tr><td>52<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><\/tr><tr><td>53<\/td><td>x<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>&#8211;<\/td><\/tr><tr><td>54<\/td><td>x<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>&#8211;<\/td><\/tr><tr><td>55<\/td><td>x<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>&#8211;<\/td><\/tr><tr><td>56<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><\/tr><tr><td>57<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><td>&#8211;<\/td><\/tr><tr><td>58<\/td><td>x<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>&#8211;<\/td><\/tr><tr><td>59<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>x<\/td><\/tr><tr><td>60<\/td><td>x<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>&#8211;<\/td><\/tr><tr><td>61<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><\/tr><tr><td>62<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>x<\/td><\/tr><tr><td>63<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><\/tr><tr><td>64<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>x<\/td><\/tr><tr><td>65<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><\/tr><tr><td>66<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><\/tr><tr><td>67<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>x<\/td><\/tr><tr><td>68<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>x<\/td><\/tr><tr><td>69<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><\/tr><tr><td>70<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>x<\/td><\/tr><tr><td>71<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><\/tr><tr><td>72<\/td><td>x<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>&#8211;<\/td><\/tr><tr><td>73<\/td><td>x<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>&#8211;<\/td><\/tr><tr><td>74<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><td>&#8211;<\/td><\/tr><tr><td>75<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><\/tr><tr><td>76<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><td>&#8211;<\/td><\/tr><tr><td>77<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>x<\/td><\/tr><tr><td>78<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><\/tr><tr><td>79<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><td>&#8211;<\/td><\/tr><tr><td>80<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><td>&#8211;<\/td><\/tr><tr><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr><td><strong>Preguntas Reserva<\/strong><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr><td><strong><br><\/strong><\/td><td>A<\/td><td>B<\/td><td>C<\/td><td>D<\/td><\/tr><tr><td>1<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><td>&#8211;<\/td><\/tr><tr><td>2<\/td><td>x<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>&#8211;<\/td><\/tr><tr><td>3<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><td>&#8211;<\/td><\/tr><tr><td>4<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>x<\/td><\/tr><tr><td>5<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><\/tr><tr><td>6<\/td><td>x<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>&#8211;<\/td><\/tr><tr><td>7<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><\/tr><tr><td>8<\/td><td>&#8211;<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><\/tr><tr><td>9<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><td>&#8211;<\/td><\/tr><tr><td>10<\/td><td>&#8211;<\/td><td>x<\/td><td>&#8211;<\/td><td>&#8211;<\/td><\/tr><\/tbody><\/table>\n\n\n\n<p><\/p>\n\n\n\n<p>Para cualquier consulta sobre la mejor academia de preparaci\u00f3n de oposiciones, pod\u00e9is dirigiros a \u00e1gorAstur formaci\u00f3n:<\/p>\n\n\n\n<p><a href=\"http:\/\/agorastur.es\/oposiciones\">http:\/\/agorastur.es\/oposiciones<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Todos sabemos que hay un proceso selectivo para la provisi\u00f3n de 117 plazas del cuerpo de auxiliares administrativos de grupo C, subgrupo C2 en turno libre ordinario y libre reservado a personas con discapacidad, convocado por la resoluci\u00f3n del 23 de julio del 2018. Hemos hecho un simulacro en nuestros centros de formaci\u00f3n para preparar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2516,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[64],"tags":[169,85,75,107,157,65,158,168],"ppma_author":[259],"class_list":{"0":"post-2502","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-oposiciones","8":"tag-academia","9":"tag-administrativo","10":"tag-asturias","11":"tag-auxiliar","12":"tag-leon","13":"tag-oposiciones","14":"tag-plantillas","15":"tag-soluciones"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Plantillas de soluciones del Simulacro Auxiliar Administrativo del Principado de Asturias - blog \u00e1gorAstur Formaci\u00f3n<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/agorastur.es\/blog\/plantillas-de-soluciones-del-simulacro-auxiliar-administrativo-del-principado\/\" \/>\r\n<meta property=\"og:locale\" content=\"es_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Plantillas de soluciones del Simulacro Auxiliar Administrativo del Principado de Asturias - blog \u00e1gorAstur Formaci\u00f3n\" \/>\r\n<meta property=\"og:description\" content=\"Todos sabemos que hay un proceso selectivo para la provisi\u00f3n de 117 plazas del cuerpo de auxiliares administrativos de grupo C, subgrupo C2 en turno libre ordinario y libre reservado a personas con discapacidad, convocado por la resoluci\u00f3n del 23 de julio del 2018. Hemos hecho un simulacro en nuestros centros de formaci\u00f3n para preparar [&hellip;]\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/agorastur.es\/blog\/plantillas-de-soluciones-del-simulacro-auxiliar-administrativo-del-principado\/\" \/>\r\n<meta property=\"og:site_name\" content=\"blog \u00e1gorAstur Formaci\u00f3n\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/agorasturformacion\" \/>\r\n<meta property=\"article:published_time\" content=\"2019-04-30T08:00:42+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2019-05-29T10:23:01+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2019\/04\/plantilla-de-examen.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"800\" \/>\r\n\t<meta property=\"og:image:height\" content=\"550\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"\u00e1gorAstur Formaci\u00f3n\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:creator\" content=\"@Agorastur\" \/>\r\n<meta name=\"twitter:site\" content=\"@Agorastur\" \/>\r\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u00e1gorAstur Formaci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/plantillas-de-soluciones-del-simulacro-auxiliar-administrativo-del-principado\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/plantillas-de-soluciones-del-simulacro-auxiliar-administrativo-del-principado\\\/\"},\"author\":{\"name\":\"\u00e1gorAstur Formaci\u00f3n\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#\\\/schema\\\/person\\\/e22add2390185670fd9a54413f42e33e\"},\"headline\":\"Plantillas de soluciones del Simulacro Auxiliar Administrativo del Principado de Asturias\",\"datePublished\":\"2019-04-30T08:00:42+00:00\",\"dateModified\":\"2019-05-29T10:23:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/plantillas-de-soluciones-del-simulacro-auxiliar-administrativo-del-principado\\\/\"},\"wordCount\":484,\"publisher\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/plantillas-de-soluciones-del-simulacro-auxiliar-administrativo-del-principado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/plantilla-de-examen.jpg\",\"keywords\":[\"academia\",\"administrativo\",\"Asturias\",\"auxiliar\",\"le\u00f3n\",\"oposiciones\",\"plantillas\",\"soluciones\"],\"articleSection\":[\"Oposiciones\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/plantillas-de-soluciones-del-simulacro-auxiliar-administrativo-del-principado\\\/\",\"url\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/plantillas-de-soluciones-del-simulacro-auxiliar-administrativo-del-principado\\\/\",\"name\":\"Plantillas de soluciones del Simulacro Auxiliar Administrativo del Principado de Asturias - blog \u00e1gorAstur Formaci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/plantillas-de-soluciones-del-simulacro-auxiliar-administrativo-del-principado\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/plantillas-de-soluciones-del-simulacro-auxiliar-administrativo-del-principado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/plantilla-de-examen.jpg\",\"datePublished\":\"2019-04-30T08:00:42+00:00\",\"dateModified\":\"2019-05-29T10:23:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/plantillas-de-soluciones-del-simulacro-auxiliar-administrativo-del-principado\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/agorastur.es\\\/blog\\\/plantillas-de-soluciones-del-simulacro-auxiliar-administrativo-del-principado\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/plantillas-de-soluciones-del-simulacro-auxiliar-administrativo-del-principado\\\/#primaryimage\",\"url\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/plantilla-de-examen.jpg\",\"contentUrl\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/plantilla-de-examen.jpg\",\"width\":800,\"height\":550},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/plantillas-de-soluciones-del-simulacro-auxiliar-administrativo-del-principado\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u00e1gorAstur\",\"item\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oposiciones\",\"item\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/novedades\\\/oposiciones\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Plantillas de soluciones del Simulacro Auxiliar Administrativo del Principado de Asturias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/\",\"name\":\"blog \u00e1gorAstur Formaci\u00f3n\",\"description\":\"Formaci\u00f3n en Asturias y Le\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#organization\",\"name\":\"Grupo Agorastur, S.L.\",\"url\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-rrss.png\",\"contentUrl\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-rrss.png\",\"width\":512,\"height\":512,\"caption\":\"Grupo Agorastur, S.L.\"},\"image\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/agorasturformacion\",\"https:\\\/\\\/x.com\\\/Agorastur\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#\\\/schema\\\/person\\\/e22add2390185670fd9a54413f42e33e\",\"name\":\"\u00e1gorAstur Formaci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-favicon-1-96x96.png07751c8812e77018f06c4e5a1412ef3a\",\"url\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-favicon-1-96x96.png\",\"contentUrl\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-favicon-1-96x96.png\",\"caption\":\"\u00e1gorAstur Formaci\u00f3n\"},\"sameAs\":[\"http:\\\/\\\/agorastur.es\"],\"url\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/author\\\/agorastur\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Plantillas de soluciones del Simulacro Auxiliar Administrativo del Principado de Asturias - blog \u00e1gorAstur Formaci\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agorastur.es\/blog\/plantillas-de-soluciones-del-simulacro-auxiliar-administrativo-del-principado\/","og_locale":"es_ES","og_type":"article","og_title":"Plantillas de soluciones del Simulacro Auxiliar Administrativo del Principado de Asturias - blog \u00e1gorAstur Formaci\u00f3n","og_description":"Todos sabemos que hay un proceso selectivo para la provisi\u00f3n de 117 plazas del cuerpo de auxiliares administrativos de grupo C, subgrupo C2 en turno libre ordinario y libre reservado a personas con discapacidad, convocado por la resoluci\u00f3n del 23 de julio del 2018. Hemos hecho un simulacro en nuestros centros de formaci\u00f3n para preparar [&hellip;]","og_url":"https:\/\/agorastur.es\/blog\/plantillas-de-soluciones-del-simulacro-auxiliar-administrativo-del-principado\/","og_site_name":"blog \u00e1gorAstur Formaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/agorasturformacion","article_published_time":"2019-04-30T08:00:42+00:00","article_modified_time":"2019-05-29T10:23:01+00:00","og_image":[{"width":800,"height":550,"url":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2019\/04\/plantilla-de-examen.jpg","type":"image\/jpeg"}],"author":"\u00e1gorAstur Formaci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@Agorastur","twitter_site":"@Agorastur","twitter_misc":{"Escrito por":"\u00e1gorAstur Formaci\u00f3n","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agorastur.es\/blog\/plantillas-de-soluciones-del-simulacro-auxiliar-administrativo-del-principado\/#article","isPartOf":{"@id":"https:\/\/agorastur.es\/blog\/plantillas-de-soluciones-del-simulacro-auxiliar-administrativo-del-principado\/"},"author":{"name":"\u00e1gorAstur Formaci\u00f3n","@id":"https:\/\/agorastur.es\/blog\/#\/schema\/person\/e22add2390185670fd9a54413f42e33e"},"headline":"Plantillas de soluciones del Simulacro Auxiliar Administrativo del Principado de Asturias","datePublished":"2019-04-30T08:00:42+00:00","dateModified":"2019-05-29T10:23:01+00:00","mainEntityOfPage":{"@id":"https:\/\/agorastur.es\/blog\/plantillas-de-soluciones-del-simulacro-auxiliar-administrativo-del-principado\/"},"wordCount":484,"publisher":{"@id":"https:\/\/agorastur.es\/blog\/#organization"},"image":{"@id":"https:\/\/agorastur.es\/blog\/plantillas-de-soluciones-del-simulacro-auxiliar-administrativo-del-principado\/#primaryimage"},"thumbnailUrl":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2019\/04\/plantilla-de-examen.jpg","keywords":["academia","administrativo","Asturias","auxiliar","le\u00f3n","oposiciones","plantillas","soluciones"],"articleSection":["Oposiciones"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/agorastur.es\/blog\/plantillas-de-soluciones-del-simulacro-auxiliar-administrativo-del-principado\/","url":"https:\/\/agorastur.es\/blog\/plantillas-de-soluciones-del-simulacro-auxiliar-administrativo-del-principado\/","name":"Plantillas de soluciones del Simulacro Auxiliar Administrativo del Principado de Asturias - blog \u00e1gorAstur Formaci\u00f3n","isPartOf":{"@id":"https:\/\/agorastur.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agorastur.es\/blog\/plantillas-de-soluciones-del-simulacro-auxiliar-administrativo-del-principado\/#primaryimage"},"image":{"@id":"https:\/\/agorastur.es\/blog\/plantillas-de-soluciones-del-simulacro-auxiliar-administrativo-del-principado\/#primaryimage"},"thumbnailUrl":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2019\/04\/plantilla-de-examen.jpg","datePublished":"2019-04-30T08:00:42+00:00","dateModified":"2019-05-29T10:23:01+00:00","breadcrumb":{"@id":"https:\/\/agorastur.es\/blog\/plantillas-de-soluciones-del-simulacro-auxiliar-administrativo-del-principado\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agorastur.es\/blog\/plantillas-de-soluciones-del-simulacro-auxiliar-administrativo-del-principado\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agorastur.es\/blog\/plantillas-de-soluciones-del-simulacro-auxiliar-administrativo-del-principado\/#primaryimage","url":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2019\/04\/plantilla-de-examen.jpg","contentUrl":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2019\/04\/plantilla-de-examen.jpg","width":800,"height":550},{"@type":"BreadcrumbList","@id":"https:\/\/agorastur.es\/blog\/plantillas-de-soluciones-del-simulacro-auxiliar-administrativo-del-principado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u00e1gorAstur","item":"https:\/\/agorastur.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Oposiciones","item":"https:\/\/agorastur.es\/blog\/novedades\/oposiciones\/"},{"@type":"ListItem","position":3,"name":"Plantillas de soluciones del Simulacro Auxiliar Administrativo del Principado de Asturias"}]},{"@type":"WebSite","@id":"https:\/\/agorastur.es\/blog\/#website","url":"https:\/\/agorastur.es\/blog\/","name":"blog \u00e1gorAstur Formaci\u00f3n","description":"Formaci\u00f3n en Asturias y Le\u00f3n","publisher":{"@id":"https:\/\/agorastur.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agorastur.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/agorastur.es\/blog\/#organization","name":"Grupo Agorastur, S.L.","url":"https:\/\/agorastur.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agorastur.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/03\/cropped-rrss.png","contentUrl":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/03\/cropped-rrss.png","width":512,"height":512,"caption":"Grupo Agorastur, S.L."},"image":{"@id":"https:\/\/agorastur.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/agorasturformacion","https:\/\/x.com\/Agorastur"]},{"@type":"Person","@id":"https:\/\/agorastur.es\/blog\/#\/schema\/person\/e22add2390185670fd9a54413f42e33e","name":"\u00e1gorAstur Formaci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/03\/cropped-favicon-1-96x96.png07751c8812e77018f06c4e5a1412ef3a","url":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/03\/cropped-favicon-1-96x96.png","contentUrl":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/03\/cropped-favicon-1-96x96.png","caption":"\u00e1gorAstur Formaci\u00f3n"},"sameAs":["http:\/\/agorastur.es"],"url":"https:\/\/agorastur.es\/blog\/author\/agorastur\/"}]}},"jetpack_featured_media_url":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2019\/04\/plantilla-de-examen.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8kSRz-Em","jetpack-related-posts":[{"id":2724,"url":"https:\/\/agorastur.es\/blog\/plantillas-simulacro-auxiliar-administrativo-del-estado\/","url_meta":{"origin":2502,"position":0},"title":"Plantillas simulacro Auxiliar Administrativo del Estado","author":"\u00e1gorAstur Formaci\u00f3n","date":"03\/10\/2019","format":false,"excerpt":"La preparaci\u00f3n de las oposiciones requiere sacrificio, constancia, tenacidad y tiempo por parte del alumnado y del profesorado. Como parte de la formaci\u00f3n, hacemos simulacros de los ex\u00e1menes para ayudar a prevenir nervios, planificar y visualizar de la mejor manera posible las pruebas. La mejor formaci\u00f3n la encontrar\u00e1s en \u00e1gorAstur\u2026","rel":"","context":"En \u00abOposiciones\u00bb","block_context":{"text":"Oposiciones","link":"https:\/\/agorastur.es\/blog\/novedades\/oposiciones\/"},"img":{"alt_text":"","src":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2019\/10\/smile-4468552_1280.jpg","width":350,"height":200,"srcset":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2019\/10\/smile-4468552_1280.jpg 1x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2019\/10\/smile-4468552_1280.jpg 1.5x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2019\/10\/smile-4468552_1280.jpg 2x"},"classes":[]},{"id":2364,"url":"https:\/\/agorastur.es\/blog\/plantillas-del-simulacro-del-sespa\/","url_meta":{"origin":2502,"position":1},"title":"Plantillas del simulacro del SESPA","author":"\u00e1gorAstur Formaci\u00f3n","date":"22\/02\/2019","format":false,"excerpt":"Como lo prometido es deuda, os dejamos las plantillas de los simulacros de los ex\u00e1menes del SESPA que hab\u00e9is realizado en vuestras respectivas sedes. Os dejamos el pdf de Celador:https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2019\/02\/CELADOR-RESPUESTAS.pdf El de Auxiliar de enfermer\u00eda: https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2019\/02\/SIMULACRO-COMPLETO-AUX.ENFERMERIA-SESPA-RESPUESTAS.pdf Y el de Auxiliar administrativo: https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2019\/02\/simulacro-AUX-ADM-SESPA-RESPUESTAS-1-.pdf Sin duda un gran ejercicio de preparaci\u00f3n para\u2026","rel":"","context":"En \u00abOposiciones\u00bb","block_context":{"text":"Oposiciones","link":"https:\/\/agorastur.es\/blog\/novedades\/oposiciones\/"},"img":{"alt_text":"selectividad","src":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2017\/02\/1d3343cc7d19f8182fcb5f3dfbb39ffb-e1487752446725.jpg","width":350,"height":200,"srcset":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2017\/02\/1d3343cc7d19f8182fcb5f3dfbb39ffb-e1487752446725.jpg 1x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2017\/02\/1d3343cc7d19f8182fcb5f3dfbb39ffb-e1487752446725.jpg 1.5x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2017\/02\/1d3343cc7d19f8182fcb5f3dfbb39ffb-e1487752446725.jpg 2x"},"classes":[]},{"id":2545,"url":"https:\/\/agorastur.es\/blog\/plantilla-definitiva-oposicion-auxiliar-administrativo-asturias\/","url_meta":{"origin":2502,"position":2},"title":"Plantilla definitiva Oposici\u00f3n Auxiliar Administrativo del Principado de Asturias","author":"\u00e1gorAstur Formaci\u00f3n","date":"29\/05\/2019","format":false,"excerpt":"Ya ha salido la plantilla definitiva de respuestas del examen del d\u00eda 25 de abril del 2019, podr\u00e9is comprobar vuestros resultados en ella. Os dejamos con las respuestas definitivas de la oposici\u00f3n de auxiliar administrativo del Principado de Asturias. \u00a0 A B C D 1 X\u00a0 \u00a0 \u00a0 \u00a0 2\u2026","rel":"","context":"En \u00abOposiciones\u00bb","block_context":{"text":"Oposiciones","link":"https:\/\/agorastur.es\/blog\/novedades\/oposiciones\/"},"img":{"alt_text":"","src":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2019\/05\/book-2619909_1280.jpg","width":350,"height":200,"srcset":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2019\/05\/book-2619909_1280.jpg 1x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2019\/05\/book-2619909_1280.jpg 1.5x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2019\/05\/book-2619909_1280.jpg 2x"},"classes":[]},{"id":2431,"url":"https:\/\/agorastur.es\/blog\/plantillas-provisionales-examen-sespa\/","url_meta":{"origin":2502,"position":3},"title":"Plantillas provisionales examen Auxiliar Administrativo del SESPA","author":"\u00e1gorAstur Formaci\u00f3n","date":"09\/04\/2019","format":false,"excerpt":"Plantillas provisionales examen SESPA Queremos que siempre teng\u00e1is la mayor y m\u00e1s completa informaci\u00f3n, esperamos que os haya salido fenomenal el examen de auxiliar administrativo del SESPA, cuyas pruebas se han hecho este fin de semana en Gij\u00f3n. Os dejamos las plantillas provisionales de correcci\u00f3n de los ex\u00e1menes, tanto de\u2026","rel":"","context":"En \u00abOposiciones\u00bb","block_context":{"text":"Oposiciones","link":"https:\/\/agorastur.es\/blog\/novedades\/oposiciones\/"},"img":{"alt_text":"","src":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2019\/04\/evaluation.jpg","width":350,"height":200,"srcset":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2019\/04\/evaluation.jpg 1x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2019\/04\/evaluation.jpg 1.5x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2019\/04\/evaluation.jpg 2x"},"classes":[]},{"id":2080,"url":"https:\/\/agorastur.es\/blog\/convocatoria-sespa\/","url_meta":{"origin":2502,"position":4},"title":"Convocatoria SESPA, 1430 plazas p\u00fablicas","author":"\u00e1gorAstur Formaci\u00f3n","date":"09\/08\/2018","format":false,"excerpt":"CONVOCATORIA DEL SESPA: \u00a1Hoy se acaban de publicar las convocatorias del Servicio de Salud del Principado de Asturias con un gran n\u00famero de plazas, 232 plazas de auxiliar administrativo, 399 de celador y 799 de auxiliar de enfermer\u00eda! Resoluci\u00f3n de 6 de agosto de 2018, de la Direcci\u00f3n Gerencia del\u2026","rel":"","context":"En \u00abEmpleo\u00bb","block_context":{"text":"Empleo","link":"https:\/\/agorastur.es\/blog\/novedades\/empleo\/"},"img":{"alt_text":"","src":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2018\/08\/OP.png","width":350,"height":200,"srcset":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2018\/08\/OP.png 1x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2018\/08\/OP.png 1.5x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2018\/08\/OP.png 2x"},"classes":[]},{"id":1450,"url":"https:\/\/agorastur.es\/blog\/convocatoria-oposiciones-auxiliar-administrativo\/","url_meta":{"origin":2502,"position":5},"title":"Convocatoria de Oposiciones a Auxiliar Administrativo","author":"\u00e1gorAstur Formaci\u00f3n","date":"12\/05\/2017","format":false,"excerpt":"Hoy se ha publicado la convocatoria para Oposiciones a Auxiliar Administrativo para el Ayuntamiento de Pola de Siero. El previsible incremento de las plazas a convocar est\u00e1 disparando el inter\u00e9s de los opositores, en \u00e1gorAstur formaci\u00f3n os ofrecemos la posibilidad de prepararlas de forma seria y concienzuda. El poder optar\u2026","rel":"","context":"En \u00abEmpleo\u00bb","block_context":{"text":"Empleo","link":"https:\/\/agorastur.es\/blog\/novedades\/empleo\/"},"img":{"alt_text":"Convocatoria Oposiciones Auxiliar Administrativo","src":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2017\/05\/Oposiciones-Auxiliar-Administrativo.jpg","width":350,"height":200,"srcset":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2017\/05\/Oposiciones-Auxiliar-Administrativo.jpg 1x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2017\/05\/Oposiciones-Auxiliar-Administrativo.jpg 1.5x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2017\/05\/Oposiciones-Auxiliar-Administrativo.jpg 2x"},"classes":[]}],"authors":[{"term_id":259,"user_id":1,"is_guest":0,"slug":"agorastur","display_name":"\u00e1gorAstur Formaci\u00f3n","avatar_url":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/03\/cropped-favicon-1-96x96.png","1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/posts\/2502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/comments?post=2502"}],"version-history":[{"count":9,"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/posts\/2502\/revisions"}],"predecessor-version":[{"id":2554,"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/posts\/2502\/revisions\/2554"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/media\/2516"}],"wp:attachment":[{"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/media?parent=2502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/categories?post=2502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/tags?post=2502"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/ppma_author?post=2502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}