{"id":1780,"date":"2018-01-31T10:03:35","date_gmt":"2018-01-31T09:03:35","guid":{"rendered":"https:\/\/agorastur.es\/blog\/?p=1780"},"modified":"2018-02-13T16:32:06","modified_gmt":"2018-02-13T15:32:06","slug":"opinion-de-alumnos-curso-asesoria","status":"publish","type":"post","link":"https:\/\/agorastur.es\/blog\/opinion-de-alumnos-curso-asesoria\/","title":{"rendered":"Opiniones de alumnos (Marbelis Hern\u00e1ndez y Pedro Fueyo)"},"content":{"rendered":"<p><strong>Opiniones de nuestros alumnos del curso Asesor\u00eda fiscal, laboral y contable, Marbelis Hern\u00e1ndez y Pedro Fueyo, que nos llenan de orgullo<\/strong>. Tras un gran esfuerzo y constancia han terminado con \u00e9xito su formaci\u00f3n como <a href=\"http:\/\/agorastur.es\/curso-asesoria-laboral-fiscal-y-contable\">asesores fiscales, laborales y contables<\/a>.<\/p>\n<p>Una vez m\u00e1s, <strong>otros alumnos m\u00e1s que satisfechos<\/strong> con la formaci\u00f3n recibida. Te dejamos con su opini\u00f3n:<br \/>\n<!--more--><\/p>\n<p><strong>Marbelis Hern\u00e1ndez:<\/strong><br \/>\n<em>Un curso muy completo, unos materiales de estudio y parte pr\u00e1ctica que merecen la pena. La experiencia personal con los tutores ha sido maravillosa, ya que adem\u00e1s de su profesionalidad en la formaci\u00f3n, muestran un alto grado de inter\u00e9s personal en los alumnos, cosa que no es com\u00fan en el resto de centros de formaci\u00f3n que he conocido.<\/em><\/p>\n<p><strong>El m\u00e9todo de estudio es personal<\/strong>, seg\u00fan la necesidad del alumno, tienen una gran paciencia para impartir los contenidos y hacerlos m\u00e1s amenos y did\u00e1cticos. <strong>La disponibilidad horaria y los esfuerzos para poder adaptarse a ti<\/strong>, quedan patentes cada d\u00eda. <strong>Te orientan y preparan para enfrentarte al mundo laboral real<\/strong>, en lo que realmente necesitas para desempe\u00f1ar tus funciones en un lugar de trabajo.<\/p>\n<p><strong>Pedro Fueyo:<\/strong><br \/>\n<em>Mi nombre es Pedro Fueyo, he realizado el Curso de Asesor\u00eda Laboral, Fiscal y Contable en \u00e1gorAstur Formaci\u00f3n en su centro en la Calle Marqu\u00e9s de Casa Vald\u00e9s 83 en Gij\u00f3n.<br \/>\nDesde el punto de vista humano, el trato recibido por mis dos tutoras Cristina y Almudena ha sido fant\u00e1stico, ya que te hacen sentir como en casa.<br \/>\nDesde el punto de vista t\u00e9cnico, el centro dispone de amplias aulas de estudio donde se imparten seminarios, todo ello en un entorno acogedor.<br \/>\nMe parece un lugar id\u00f3neo tanto para especializarte en tus estudios como para retomar la formaci\u00f3n no realizado en el pasado, ya que ofrece ambas opciones.<br \/>\nTras mi paso por \u00e1gorAstur, estuve haciendo pr\u00e1cticas en una empresa y me contrataron al finalizar las mismas, por tanto en ese sentido estoy plenamente agradecido.<br \/>\nRecomiendo \u00e1gorAstur para todos aquellos que quieran realizar estudios y no sepan en qu\u00e9 lugar llevarlos a cabo, ya que adem\u00e1s de centro de formaci\u00f3n tambi\u00e9n son agencia de colocaci\u00f3n, lo que favorece en gran medida una salida laboral.<\/em><\/p>\n<p>Muchas gracias por vuestras opiniones, ha sido un placer guiaros en vuestra formaci\u00f3n. Nos complace enormemente haber cumplido vuestras expectativas y sobre todo queremos dejar constancia de que haremos todo lo que est\u00e9 de nuestra mano para poder seguir ayud\u00e1ndoos a cumplir vuestros objetivos. La formaci\u00f3n tiene una gran parte vocacional y el saber que podemos incrementar exponencialmente las posibilidades de nuestros alumnos, nos ayuda a mantener claros nuestras metas. Gracias por vuestras palabras, que nos ayudan a continuar en el buen camino.<\/p>\n<p>Si ten\u00e9is alguna duda de nuestra oferta formativa, s\u00f3lo ten\u00e9is que solicitar informaci\u00f3n sin compromiso, te sorprenderemos. Disponemos de centros en Oviedo, Gij\u00f3n, Avil\u00e9s y Langreo para mayor disposici\u00f3n para nuestros alumnos.<\/p>\n<p><strong>Como siempre nos puedes encontrar en \u00e1gorAstur formaci\u00f3n, tu centro de confianza<\/strong>:<br \/>\n<a href=\"http:\/\/agorastur.es\/\">http:\/\/agorastur.es<\/a><\/p>\n<p><strong>Tambi\u00e9n nos puedes seguir en facebook, para conocer todas las novedades<\/strong>:<br \/>\n<a href=\"https:\/\/www.facebook.com\/Agorastur\/\">https:\/\/www.facebook.com\/Agorastur\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Opiniones de nuestros alumnos del curso Asesor\u00eda fiscal, laboral y contable, Marbelis Hern\u00e1ndez y Pedro Fueyo, que nos llenan de orgullo. Tras un gran esfuerzo y constancia han terminado con \u00e9xito su formaci\u00f3n como asesores fiscales, laborales y contables. Una vez m\u00e1s, otros alumnos m\u00e1s que satisfechos con la formaci\u00f3n recibida. Te dejamos con su [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1849,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[72],"tags":[121,101,102,122,120],"ppma_author":[259],"class_list":{"0":"post-1780","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-casos-de-exito","8":"tag-cursos","9":"tag-exito","10":"tag-formacion","11":"tag-opiniones","12":"tag-superacion"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Opini\u00f3n de Marbelis Hern\u00e1ndez, alumna de \u00e1gorAstur formaci\u00f3n<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/agorastur.es\/blog\/opinion-de-alumnos-curso-asesoria\/\" \/>\r\n<meta property=\"og:locale\" content=\"es_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Opini\u00f3n de Marbelis Hern\u00e1ndez, alumna de \u00e1gorAstur formaci\u00f3n\" \/>\r\n<meta property=\"og:description\" content=\"Opiniones de nuestros alumnos del curso Asesor\u00eda fiscal, laboral y contable, Marbelis Hern\u00e1ndez y Pedro Fueyo, que nos llenan de orgullo. Tras un gran esfuerzo y constancia han terminado con \u00e9xito su formaci\u00f3n como asesores fiscales, laborales y contables. Una vez m\u00e1s, otros alumnos m\u00e1s que satisfechos con la formaci\u00f3n recibida. Te dejamos con su [&hellip;]\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/agorastur.es\/blog\/opinion-de-alumnos-curso-asesoria\/\" \/>\r\n<meta property=\"og:site_name\" content=\"blog \u00e1gorAstur Formaci\u00f3n\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/agorasturformacion\" \/>\r\n<meta property=\"article:published_time\" content=\"2018-01-31T09:03:35+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2018-02-13T15:32:06+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2018\/01\/PUEDES.png\" \/>\r\n\t<meta property=\"og:image:width\" content=\"800\" \/>\r\n\t<meta property=\"og:image:height\" content=\"550\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\r\n<meta name=\"author\" content=\"\u00e1gorAstur Formaci\u00f3n\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:creator\" content=\"@Agorastur\" \/>\r\n<meta name=\"twitter:site\" content=\"@Agorastur\" \/>\r\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u00e1gorAstur Formaci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/opinion-de-alumnos-curso-asesoria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/opinion-de-alumnos-curso-asesoria\\\/\"},\"author\":{\"name\":\"\u00e1gorAstur Formaci\u00f3n\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#\\\/schema\\\/person\\\/e22add2390185670fd9a54413f42e33e\"},\"headline\":\"Opiniones de alumnos (Marbelis Hern\u00e1ndez y Pedro Fueyo)\",\"datePublished\":\"2018-01-31T09:03:35+00:00\",\"dateModified\":\"2018-02-13T15:32:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/opinion-de-alumnos-curso-asesoria\\\/\"},\"wordCount\":555,\"publisher\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/opinion-de-alumnos-curso-asesoria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/PUEDES.png\",\"keywords\":[\"cursos\",\"\u00e9xito\",\"formaci\u00f3n\",\"opiniones\",\"superaci\u00f3n\"],\"articleSection\":[\"Casos de \u00c9xito\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/opinion-de-alumnos-curso-asesoria\\\/\",\"url\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/opinion-de-alumnos-curso-asesoria\\\/\",\"name\":\"Opini\u00f3n de Marbelis Hern\u00e1ndez, alumna de \u00e1gorAstur formaci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/opinion-de-alumnos-curso-asesoria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/opinion-de-alumnos-curso-asesoria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/PUEDES.png\",\"datePublished\":\"2018-01-31T09:03:35+00:00\",\"dateModified\":\"2018-02-13T15:32:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/opinion-de-alumnos-curso-asesoria\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/agorastur.es\\\/blog\\\/opinion-de-alumnos-curso-asesoria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/opinion-de-alumnos-curso-asesoria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/PUEDES.png\",\"contentUrl\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/PUEDES.png\",\"width\":800,\"height\":550},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/opinion-de-alumnos-curso-asesoria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u00e1gorAstur\",\"item\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Casos de \u00c9xito\",\"item\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/novedades\\\/casos-de-exito\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Opiniones de alumnos (Marbelis Hern\u00e1ndez y Pedro Fueyo)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/\",\"name\":\"blog \u00e1gorAstur Formaci\u00f3n\",\"description\":\"Formaci\u00f3n en Asturias y Le\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#organization\",\"name\":\"Grupo Agorastur, S.L.\",\"url\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-rrss.png\",\"contentUrl\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-rrss.png\",\"width\":512,\"height\":512,\"caption\":\"Grupo Agorastur, S.L.\"},\"image\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/agorasturformacion\",\"https:\\\/\\\/x.com\\\/Agorastur\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#\\\/schema\\\/person\\\/e22add2390185670fd9a54413f42e33e\",\"name\":\"\u00e1gorAstur Formaci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-favicon-1-96x96.png07751c8812e77018f06c4e5a1412ef3a\",\"url\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-favicon-1-96x96.png\",\"contentUrl\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-favicon-1-96x96.png\",\"caption\":\"\u00e1gorAstur Formaci\u00f3n\"},\"sameAs\":[\"http:\\\/\\\/agorastur.es\"],\"url\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/author\\\/agorastur\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Opini\u00f3n de Marbelis Hern\u00e1ndez, alumna de \u00e1gorAstur formaci\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agorastur.es\/blog\/opinion-de-alumnos-curso-asesoria\/","og_locale":"es_ES","og_type":"article","og_title":"Opini\u00f3n de Marbelis Hern\u00e1ndez, alumna de \u00e1gorAstur formaci\u00f3n","og_description":"Opiniones de nuestros alumnos del curso Asesor\u00eda fiscal, laboral y contable, Marbelis Hern\u00e1ndez y Pedro Fueyo, que nos llenan de orgullo. Tras un gran esfuerzo y constancia han terminado con \u00e9xito su formaci\u00f3n como asesores fiscales, laborales y contables. Una vez m\u00e1s, otros alumnos m\u00e1s que satisfechos con la formaci\u00f3n recibida. Te dejamos con su [&hellip;]","og_url":"https:\/\/agorastur.es\/blog\/opinion-de-alumnos-curso-asesoria\/","og_site_name":"blog \u00e1gorAstur Formaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/agorasturformacion","article_published_time":"2018-01-31T09:03:35+00:00","article_modified_time":"2018-02-13T15:32:06+00:00","og_image":[{"width":800,"height":550,"url":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2018\/01\/PUEDES.png","type":"image\/png"}],"author":"\u00e1gorAstur Formaci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@Agorastur","twitter_site":"@Agorastur","twitter_misc":{"Escrito por":"\u00e1gorAstur Formaci\u00f3n","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agorastur.es\/blog\/opinion-de-alumnos-curso-asesoria\/#article","isPartOf":{"@id":"https:\/\/agorastur.es\/blog\/opinion-de-alumnos-curso-asesoria\/"},"author":{"name":"\u00e1gorAstur Formaci\u00f3n","@id":"https:\/\/agorastur.es\/blog\/#\/schema\/person\/e22add2390185670fd9a54413f42e33e"},"headline":"Opiniones de alumnos (Marbelis Hern\u00e1ndez y Pedro Fueyo)","datePublished":"2018-01-31T09:03:35+00:00","dateModified":"2018-02-13T15:32:06+00:00","mainEntityOfPage":{"@id":"https:\/\/agorastur.es\/blog\/opinion-de-alumnos-curso-asesoria\/"},"wordCount":555,"publisher":{"@id":"https:\/\/agorastur.es\/blog\/#organization"},"image":{"@id":"https:\/\/agorastur.es\/blog\/opinion-de-alumnos-curso-asesoria\/#primaryimage"},"thumbnailUrl":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2018\/01\/PUEDES.png","keywords":["cursos","\u00e9xito","formaci\u00f3n","opiniones","superaci\u00f3n"],"articleSection":["Casos de \u00c9xito"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/agorastur.es\/blog\/opinion-de-alumnos-curso-asesoria\/","url":"https:\/\/agorastur.es\/blog\/opinion-de-alumnos-curso-asesoria\/","name":"Opini\u00f3n de Marbelis Hern\u00e1ndez, alumna de \u00e1gorAstur formaci\u00f3n","isPartOf":{"@id":"https:\/\/agorastur.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agorastur.es\/blog\/opinion-de-alumnos-curso-asesoria\/#primaryimage"},"image":{"@id":"https:\/\/agorastur.es\/blog\/opinion-de-alumnos-curso-asesoria\/#primaryimage"},"thumbnailUrl":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2018\/01\/PUEDES.png","datePublished":"2018-01-31T09:03:35+00:00","dateModified":"2018-02-13T15:32:06+00:00","breadcrumb":{"@id":"https:\/\/agorastur.es\/blog\/opinion-de-alumnos-curso-asesoria\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agorastur.es\/blog\/opinion-de-alumnos-curso-asesoria\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agorastur.es\/blog\/opinion-de-alumnos-curso-asesoria\/#primaryimage","url":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2018\/01\/PUEDES.png","contentUrl":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2018\/01\/PUEDES.png","width":800,"height":550},{"@type":"BreadcrumbList","@id":"https:\/\/agorastur.es\/blog\/opinion-de-alumnos-curso-asesoria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u00e1gorAstur","item":"https:\/\/agorastur.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Casos de \u00c9xito","item":"https:\/\/agorastur.es\/blog\/novedades\/casos-de-exito\/"},{"@type":"ListItem","position":3,"name":"Opiniones de alumnos (Marbelis Hern\u00e1ndez y Pedro Fueyo)"}]},{"@type":"WebSite","@id":"https:\/\/agorastur.es\/blog\/#website","url":"https:\/\/agorastur.es\/blog\/","name":"blog \u00e1gorAstur Formaci\u00f3n","description":"Formaci\u00f3n en Asturias y Le\u00f3n","publisher":{"@id":"https:\/\/agorastur.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agorastur.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/agorastur.es\/blog\/#organization","name":"Grupo Agorastur, S.L.","url":"https:\/\/agorastur.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agorastur.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/03\/cropped-rrss.png","contentUrl":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/03\/cropped-rrss.png","width":512,"height":512,"caption":"Grupo Agorastur, S.L."},"image":{"@id":"https:\/\/agorastur.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/agorasturformacion","https:\/\/x.com\/Agorastur"]},{"@type":"Person","@id":"https:\/\/agorastur.es\/blog\/#\/schema\/person\/e22add2390185670fd9a54413f42e33e","name":"\u00e1gorAstur Formaci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/03\/cropped-favicon-1-96x96.png07751c8812e77018f06c4e5a1412ef3a","url":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/03\/cropped-favicon-1-96x96.png","contentUrl":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/03\/cropped-favicon-1-96x96.png","caption":"\u00e1gorAstur Formaci\u00f3n"},"sameAs":["http:\/\/agorastur.es"],"url":"https:\/\/agorastur.es\/blog\/author\/agorastur\/"}]}},"jetpack_featured_media_url":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2018\/01\/PUEDES.png","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8kSRz-sI","jetpack-related-posts":[{"id":1668,"url":"https:\/\/agorastur.es\/blog\/cum-laude-2017-los-alumnos-opinan\/","url_meta":{"origin":1780,"position":0},"title":"CUM LAUDE 2017: los alumnos opinan","author":"\u00e1gorAstur Formaci\u00f3n","date":"20\/11\/2017","format":false,"excerpt":"\u00a1CUM LAUDE 2017, gracias! En primer lugar, nos gustar\u00eda agradecer a todo nuestro personal docente el excelente desempe\u00f1o en sus labores, sin ellos no ser\u00eda posible este reconocimiento, pues son el motor de nuestra base, la formaci\u00f3n. Es gracias a ellos que nuestros alumnos tienen un gran concepto de nuestra\u2026","rel":"","context":"En \u00abCasos de \u00c9xito\u00bb","block_context":{"text":"Casos de \u00c9xito","link":"https:\/\/agorastur.es\/blog\/novedades\/casos-de-exito\/"},"img":{"alt_text":"","src":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2017\/11\/CUM-LAUDE.png","width":350,"height":200,"srcset":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2017\/11\/CUM-LAUDE.png 1x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2017\/11\/CUM-LAUDE.png 1.5x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2017\/11\/CUM-LAUDE.png 2x"},"classes":[]},{"id":1734,"url":"https:\/\/agorastur.es\/blog\/otro-gran-exito-agorastur-formacion\/","url_meta":{"origin":1780,"position":1},"title":"\u00a1Otro gran \u00e9xito en \u00e1gorAstur formaci\u00f3n!","author":"\u00e1gorAstur Formaci\u00f3n","date":"18\/12\/2017","format":false,"excerpt":"Hoy queremos contaros la experiencia y \u00e9xito de otra de nuestras alumnas, Montserrat Cotarelo, que tras formarse en Secretariado de Direcci\u00f3n en \u00e1gorAstur formaci\u00f3n, ha sido contratada en el mismo despacho de abogados en el que realiz\u00f3 las pr\u00e1cticas con \u00e1gorAstur (Celem\u00edn Patrimonio, C.B.). Con esfuerzo y dedicaci\u00f3n\u00a0ha logrado sus\u2026","rel":"","context":"En \u00abCasos de \u00c9xito\u00bb","block_context":{"text":"Casos de \u00c9xito","link":"https:\/\/agorastur.es\/blog\/novedades\/casos-de-exito\/"},"img":{"alt_text":"","src":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2017\/12\/Abogados.png","width":350,"height":200,"srcset":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2017\/12\/Abogados.png 1x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2017\/12\/Abogados.png 1.5x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2017\/12\/Abogados.png 2x"},"classes":[]},{"id":1513,"url":"https:\/\/agorastur.es\/blog\/margarita-estrada-exito\/","url_meta":{"origin":1780,"position":2},"title":"Margarita Estrada, otro \u00e9xito","author":"\u00e1gorAstur Formaci\u00f3n","date":"22\/06\/2017","format":false,"excerpt":"Para los que nos conocen, saben que nos desvivimos para brindar a nuestros alumnos la mejor formaci\u00f3n, el mayor desempe\u00f1o y esfuerzo para que logr\u00e9is todos vuestros objetivos a nivel profesional y de conocimientos, siempre en la b\u00fasqueda continua del \u00e9xito. Hoy tenemos que agradecer las palabras de nuestra alumna\u2026","rel":"","context":"En \u00abCasos de \u00c9xito\u00bb","block_context":{"text":"Casos de \u00c9xito","link":"https:\/\/agorastur.es\/blog\/novedades\/casos-de-exito\/"},"img":{"alt_text":"","src":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2017\/06\/Margarita-Estrada.png","width":350,"height":200,"srcset":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2017\/06\/Margarita-Estrada.png 1x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2017\/06\/Margarita-Estrada.png 1.5x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2017\/06\/Margarita-Estrada.png 2x"},"classes":[]},{"id":1409,"url":"https:\/\/agorastur.es\/blog\/experiencia-ha-francamente-positiva-actualmente-trabajo-asturias\/","url_meta":{"origin":1780,"position":3},"title":"Mi experiencia ha sido francamente positiva, actualmente trabajo en Asturias","author":"\u00e1gorAstur Formaci\u00f3n","date":"19\/04\/2017","format":false,"excerpt":"Queremos compartir\u00a0la opini\u00f3n de uno de nuestros alumnos, un caso de \u00e9xito de nuestro centro de formaci\u00f3n que nos alegra y nos da m\u00e1s fuerzas para continuar formando y ayudando a m\u00e1s j\u00f3venes de Asturias. Gracias Pedro por tus palabras! No conozco la experiencia del resto de alumnos que han\u2026","rel":"","context":"En \u00abCasos de \u00c9xito\u00bb","block_context":{"text":"Casos de \u00c9xito","link":"https:\/\/agorastur.es\/blog\/novedades\/casos-de-exito\/"},"img":{"alt_text":"pedro-arrojo-moutas","src":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2017\/04\/pedro-arrojo-moutas.jpg","width":350,"height":200,"srcset":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2017\/04\/pedro-arrojo-moutas.jpg 1x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2017\/04\/pedro-arrojo-moutas.jpg 1.5x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2017\/04\/pedro-arrojo-moutas.jpg 2x"},"classes":[]},{"id":1898,"url":"https:\/\/agorastur.es\/blog\/opinion-de-maria-caballero\/","url_meta":{"origin":1780,"position":4},"title":"Opini\u00f3n de Mar\u00eda Caballero","author":"\u00e1gorAstur Formaci\u00f3n","date":"21\/03\/2018","format":false,"excerpt":"Queremos compartir con todos vosotros las experiencias de nuestros alumnos, personas que se pueden encontrar en circunstancias similares a las vuestras, buscando salidas laborales o complementar su CV para mejorar laboralmente. Porque en \u00e1gorAstur formaci\u00f3n buscamos impartir la mejor de las formaciones en todos los campos, vuestra confianza es nuestro\u2026","rel":"","context":"En \u00abCasos de \u00c9xito\u00bb","block_context":{"text":"Casos de \u00c9xito","link":"https:\/\/agorastur.es\/blog\/novedades\/casos-de-exito\/"},"img":{"alt_text":"","src":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2018\/03\/Imagen1.png","width":350,"height":200,"srcset":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2018\/03\/Imagen1.png 1x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2018\/03\/Imagen1.png 1.5x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2018\/03\/Imagen1.png 2x"},"classes":[]},{"id":1532,"url":"https:\/\/agorastur.es\/blog\/opinion-cintya-cristina\/","url_meta":{"origin":1780,"position":5},"title":"Opini\u00f3n de Cintya Cristina","author":"\u00e1gorAstur Formaci\u00f3n","date":"03\/07\/2017","format":false,"excerpt":"Hoy queremos compartir el buen sabor de boca que nos deja la opini\u00f3n de una de nuestras alumnas, Cintya Cristina, que tras su esfuerzo y buen hacer ha terminado con \u00e9xito su formaci\u00f3n como camarera profesional. Una vez m\u00e1s, tenemos otro caso de \u00e9xito. Aqu\u00ed os mostramos su opini\u00f3n: \u00a1\u00a1\u00a1Acabo\u2026","rel":"","context":"En \u00abCasos de \u00c9xito\u00bb","block_context":{"text":"Casos de \u00c9xito","link":"https:\/\/agorastur.es\/blog\/novedades\/casos-de-exito\/"},"img":{"alt_text":"","src":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2017\/07\/Cynthia.png","width":350,"height":200,"srcset":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2017\/07\/Cynthia.png 1x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2017\/07\/Cynthia.png 1.5x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2017\/07\/Cynthia.png 2x"},"classes":[]}],"authors":[{"term_id":259,"user_id":1,"is_guest":0,"slug":"agorastur","display_name":"\u00e1gorAstur Formaci\u00f3n","avatar_url":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/03\/cropped-favicon-1-96x96.png","1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/posts\/1780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/comments?post=1780"}],"version-history":[{"count":9,"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/posts\/1780\/revisions"}],"predecessor-version":[{"id":1860,"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/posts\/1780\/revisions\/1860"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/media\/1849"}],"wp:attachment":[{"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/media?parent=1780"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/categories?post=1780"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/tags?post=1780"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/ppma_author?post=1780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}