{"id":14085,"date":"2025-05-05T15:10:50","date_gmt":"2025-05-05T13:10:50","guid":{"rendered":"https:\/\/agorastur.es\/blog\/?p=14085"},"modified":"2025-05-05T15:10:50","modified_gmt":"2025-05-05T13:10:50","slug":"seminarios-de-mayo-2025","status":"publish","type":"post","link":"https:\/\/agorastur.es\/blog\/seminarios-de-mayo-2025\/","title":{"rendered":"Seminarios de mayo 2025"},"content":{"rendered":"<p class=\"\" data-start=\"0\" data-end=\"58\">\ud83c\udf37 <strong data-start=\"3\" data-end=\"58\">Mayo: Mes de impulso, avance y nuevas oportunidades<\/strong><\/p>\n<p class=\"\" data-start=\"60\" data-end=\"337\">Mayo llega cargado de energ\u00eda y vitalidad, listo para acompa\u00f1arte en el camino hacia tus metas. Este mes seguimos impulsando tu desarrollo con nuestra propuesta renovada de seminarios gratuitos, enfocados en potenciar a\u00fan m\u00e1s tus habilidades y ampliar horizontes profesionales.<\/p>\n<p class=\"\" data-start=\"339\" data-end=\"585\">Te invitamos a aprovechar al m\u00e1ximo estas formaciones, dise\u00f1adas especialmente para brindarte herramientas pr\u00e1cticas que podr\u00e1s aplicar inmediatamente en tu d\u00eda a d\u00eda. Contin\u00faa creciendo, compartiendo experiencias y conquistando nuevos objetivos.<\/p>\n<p class=\"\" data-start=\"587\" data-end=\"675\">\u00a1Inscr\u00edbete ya! Ponte en contacto con tu tutor o escr\u00edbenos a <a rel=\"noopener\" data-start=\"649\" data-end=\"674\">solicitudes@agorastur.com<\/a>.<\/p>\n<p class=\"\" data-start=\"677\" data-end=\"711\">\u00a1Te esperamos para avanzar juntos!<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-14087 size-large aligncenter\" src=\"http:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/05\/calendario-seminarios-agorastur-mayo-2025-1024x617.png\" alt=\"\" width=\"1024\" height=\"617\" srcset=\"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/05\/calendario-seminarios-agorastur-mayo-2025-1024x617.png 1024w, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/05\/calendario-seminarios-agorastur-mayo-2025-300x181.png 300w, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/05\/calendario-seminarios-agorastur-mayo-2025-768x463.png 768w, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/05\/calendario-seminarios-agorastur-mayo-2025-1536x925.png 1536w, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/05\/calendario-seminarios-agorastur-mayo-2025-450x271.png 450w, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/05\/calendario-seminarios-agorastur-mayo-2025-780x470.png 780w, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/05\/calendario-seminarios-agorastur-mayo-2025-1600x964.png 1600w, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/05\/calendario-seminarios-agorastur-mayo-2025.png 1869w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ud83c\udf37 Mayo: Mes de impulso, avance y nuevas oportunidades Mayo llega cargado de energ\u00eda y vitalidad, listo para acompa\u00f1arte en el camino hacia tus metas. Este mes seguimos impulsando tu desarrollo con nuestra propuesta renovada de seminarios gratuitos, enfocados en potenciar a\u00fan m\u00e1s tus habilidades y ampliar horizontes profesionales. Te invitamos a aprovechar al m\u00e1ximo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14086,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[40],"tags":[],"ppma_author":[259],"class_list":{"0":"post-14085","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-seminarios"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Seminarios de mayo 2025 - blog \u00e1gorAstur Formaci\u00f3n<\/title>\r\n<meta name=\"description\" content=\"Seminarios \ud83c\udf37 Mayo: Mes de impulso, avance y nuevas oportunidades: Mes de renovaci\u00f3n, crecimiento y nuevos desaf\u00edos\" \/>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/agorastur.es\/blog\/seminarios-de-mayo-2025\/\" \/>\r\n<meta property=\"og:locale\" content=\"es_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Seminarios de mayo 2025 - blog \u00e1gorAstur Formaci\u00f3n\" \/>\r\n<meta property=\"og:description\" content=\"Seminarios \ud83c\udf37 Mayo: Mes de impulso, avance y nuevas oportunidades: Mes de renovaci\u00f3n, crecimiento y nuevos desaf\u00edos\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/agorastur.es\/blog\/seminarios-de-mayo-2025\/\" \/>\r\n<meta property=\"og:site_name\" content=\"blog \u00e1gorAstur Formaci\u00f3n\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/agorasturformacion\" \/>\r\n<meta property=\"article:published_time\" content=\"2025-05-05T13:10:50+00:00\" \/>\r\n<meta property=\"og:image\" content=\"http:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/05\/seminarios-mayo-2025.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\r\n\t<meta property=\"og:image:height\" content=\"630\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"\u00e1gorAstur Formaci\u00f3n\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:creator\" content=\"@Agorastur\" \/>\r\n<meta name=\"twitter:site\" content=\"@Agorastur\" \/>\r\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u00e1gorAstur Formaci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/seminarios-de-mayo-2025\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/seminarios-de-mayo-2025\\\/\"},\"author\":{\"name\":\"\u00e1gorAstur Formaci\u00f3n\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#\\\/schema\\\/person\\\/e22add2390185670fd9a54413f42e33e\"},\"headline\":\"Seminarios de mayo 2025\",\"datePublished\":\"2025-05-05T13:10:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/seminarios-de-mayo-2025\\\/\"},\"wordCount\":117,\"publisher\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/seminarios-de-mayo-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/seminarios-mayo-2025.jpg\",\"articleSection\":[\"Seminarios\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/seminarios-de-mayo-2025\\\/\",\"url\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/seminarios-de-mayo-2025\\\/\",\"name\":\"Seminarios de mayo 2025 - blog \u00e1gorAstur Formaci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/seminarios-de-mayo-2025\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/seminarios-de-mayo-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/seminarios-mayo-2025.jpg\",\"datePublished\":\"2025-05-05T13:10:50+00:00\",\"description\":\"Seminarios \ud83c\udf37 Mayo: Mes de impulso, avance y nuevas oportunidades: Mes de renovaci\u00f3n, crecimiento y nuevos desaf\u00edos\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/seminarios-de-mayo-2025\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/agorastur.es\\\/blog\\\/seminarios-de-mayo-2025\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/seminarios-de-mayo-2025\\\/#primaryimage\",\"url\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/seminarios-mayo-2025.jpg\",\"contentUrl\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/seminarios-mayo-2025.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/seminarios-de-mayo-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u00e1gorAstur\",\"item\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Seminarios\",\"item\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/novedades\\\/seminarios\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Seminarios de mayo 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/\",\"name\":\"blog \u00e1gorAstur Formaci\u00f3n\",\"description\":\"Formaci\u00f3n en Asturias y Le\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#organization\",\"name\":\"Grupo Agorastur, S.L.\",\"url\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-rrss.png\",\"contentUrl\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-rrss.png\",\"width\":512,\"height\":512,\"caption\":\"Grupo Agorastur, S.L.\"},\"image\":{\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/agorasturformacion\",\"https:\\\/\\\/x.com\\\/Agorastur\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/#\\\/schema\\\/person\\\/e22add2390185670fd9a54413f42e33e\",\"name\":\"\u00e1gorAstur Formaci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-favicon-1-96x96.png07751c8812e77018f06c4e5a1412ef3a\",\"url\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-favicon-1-96x96.png\",\"contentUrl\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-favicon-1-96x96.png\",\"caption\":\"\u00e1gorAstur Formaci\u00f3n\"},\"sameAs\":[\"http:\\\/\\\/agorastur.es\"],\"url\":\"https:\\\/\\\/agorastur.es\\\/blog\\\/author\\\/agorastur\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Seminarios de mayo 2025 - blog \u00e1gorAstur Formaci\u00f3n","description":"Seminarios \ud83c\udf37 Mayo: Mes de impulso, avance y nuevas oportunidades: Mes de renovaci\u00f3n, crecimiento y nuevos desaf\u00edos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agorastur.es\/blog\/seminarios-de-mayo-2025\/","og_locale":"es_ES","og_type":"article","og_title":"Seminarios de mayo 2025 - blog \u00e1gorAstur Formaci\u00f3n","og_description":"Seminarios \ud83c\udf37 Mayo: Mes de impulso, avance y nuevas oportunidades: Mes de renovaci\u00f3n, crecimiento y nuevos desaf\u00edos","og_url":"https:\/\/agorastur.es\/blog\/seminarios-de-mayo-2025\/","og_site_name":"blog \u00e1gorAstur Formaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/agorasturformacion","article_published_time":"2025-05-05T13:10:50+00:00","og_image":[{"width":1200,"height":630,"url":"http:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/05\/seminarios-mayo-2025.jpg","type":"image\/jpeg"}],"author":"\u00e1gorAstur Formaci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@Agorastur","twitter_site":"@Agorastur","twitter_misc":{"Escrito por":"\u00e1gorAstur Formaci\u00f3n","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agorastur.es\/blog\/seminarios-de-mayo-2025\/#article","isPartOf":{"@id":"https:\/\/agorastur.es\/blog\/seminarios-de-mayo-2025\/"},"author":{"name":"\u00e1gorAstur Formaci\u00f3n","@id":"https:\/\/agorastur.es\/blog\/#\/schema\/person\/e22add2390185670fd9a54413f42e33e"},"headline":"Seminarios de mayo 2025","datePublished":"2025-05-05T13:10:50+00:00","mainEntityOfPage":{"@id":"https:\/\/agorastur.es\/blog\/seminarios-de-mayo-2025\/"},"wordCount":117,"publisher":{"@id":"https:\/\/agorastur.es\/blog\/#organization"},"image":{"@id":"https:\/\/agorastur.es\/blog\/seminarios-de-mayo-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/05\/seminarios-mayo-2025.jpg","articleSection":["Seminarios"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/agorastur.es\/blog\/seminarios-de-mayo-2025\/","url":"https:\/\/agorastur.es\/blog\/seminarios-de-mayo-2025\/","name":"Seminarios de mayo 2025 - blog \u00e1gorAstur Formaci\u00f3n","isPartOf":{"@id":"https:\/\/agorastur.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agorastur.es\/blog\/seminarios-de-mayo-2025\/#primaryimage"},"image":{"@id":"https:\/\/agorastur.es\/blog\/seminarios-de-mayo-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/05\/seminarios-mayo-2025.jpg","datePublished":"2025-05-05T13:10:50+00:00","description":"Seminarios \ud83c\udf37 Mayo: Mes de impulso, avance y nuevas oportunidades: Mes de renovaci\u00f3n, crecimiento y nuevos desaf\u00edos","breadcrumb":{"@id":"https:\/\/agorastur.es\/blog\/seminarios-de-mayo-2025\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agorastur.es\/blog\/seminarios-de-mayo-2025\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agorastur.es\/blog\/seminarios-de-mayo-2025\/#primaryimage","url":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/05\/seminarios-mayo-2025.jpg","contentUrl":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/05\/seminarios-mayo-2025.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/agorastur.es\/blog\/seminarios-de-mayo-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u00e1gorAstur","item":"https:\/\/agorastur.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Seminarios","item":"https:\/\/agorastur.es\/blog\/novedades\/seminarios\/"},{"@type":"ListItem","position":3,"name":"Seminarios de mayo 2025"}]},{"@type":"WebSite","@id":"https:\/\/agorastur.es\/blog\/#website","url":"https:\/\/agorastur.es\/blog\/","name":"blog \u00e1gorAstur Formaci\u00f3n","description":"Formaci\u00f3n en Asturias y Le\u00f3n","publisher":{"@id":"https:\/\/agorastur.es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agorastur.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/agorastur.es\/blog\/#organization","name":"Grupo Agorastur, S.L.","url":"https:\/\/agorastur.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agorastur.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/03\/cropped-rrss.png","contentUrl":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/03\/cropped-rrss.png","width":512,"height":512,"caption":"Grupo Agorastur, S.L."},"image":{"@id":"https:\/\/agorastur.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/agorasturformacion","https:\/\/x.com\/Agorastur"]},{"@type":"Person","@id":"https:\/\/agorastur.es\/blog\/#\/schema\/person\/e22add2390185670fd9a54413f42e33e","name":"\u00e1gorAstur Formaci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/03\/cropped-favicon-1-96x96.png07751c8812e77018f06c4e5a1412ef3a","url":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/03\/cropped-favicon-1-96x96.png","contentUrl":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/03\/cropped-favicon-1-96x96.png","caption":"\u00e1gorAstur Formaci\u00f3n"},"sameAs":["http:\/\/agorastur.es"],"url":"https:\/\/agorastur.es\/blog\/author\/agorastur\/"}]}},"jetpack_featured_media_url":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/05\/seminarios-mayo-2025.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8kSRz-3Fb","jetpack-related-posts":[{"id":4218,"url":"https:\/\/agorastur.es\/blog\/seminarios-de-mayo-2023\/","url_meta":{"origin":14085,"position":0},"title":"Seminarios de Mayo 2023","author":"\u00e1gorAstur Formaci\u00f3n","date":"28\/04\/2023","format":false,"excerpt":"Los seminarios del mes de mayo ya est\u00e1n preparados para que os apunt\u00e9is a vuestro favorito. Si est\u00e1s interesado, confirma tu asistencia con tu tutor o escribi\u00e9ndonos al email\u00a0solicitudes@agorastur.com \u00a1Te esperamos!","rel":"","context":"En \u00abSeminarios\u00bb","block_context":{"text":"Seminarios","link":"https:\/\/agorastur.es\/blog\/novedades\/seminarios\/"},"img":{"alt_text":"seminarios mayo 2023","src":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2023\/04\/Blog800-\u00d7-550-px-2.webp","width":350,"height":200,"srcset":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2023\/04\/Blog800-\u00d7-550-px-2.webp 1x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2023\/04\/Blog800-\u00d7-550-px-2.webp 1.5x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2023\/04\/Blog800-\u00d7-550-px-2.webp 2x"},"classes":[]},{"id":3896,"url":"https:\/\/agorastur.es\/blog\/seminarios-de-mayo-del-2022\/","url_meta":{"origin":14085,"position":1},"title":"Seminarios de mayo del 2022","author":"\u00e1gorAstur Formaci\u00f3n","date":"06\/05\/2022","format":false,"excerpt":"Os dejamos el calendario de seminarios te\u00f3ricos y pr\u00e1cticos que se realizar\u00e1n en \u00e1gorAstur durante el mes de mayo. Primeros auxilios, t\u00e9cnicas de estudio, ingl\u00e9s, qu\u00edmica, inform\u00e1tica, jur\u00eddico, manipulador de alimentos... No dudes en apuntarte al que m\u00e1s te interese. Por favor, confirma tu asistencia con tu tutor o al\u2026","rel":"","context":"En \u00abSeminarios\u00bb","block_context":{"text":"Seminarios","link":"https:\/\/agorastur.es\/blog\/novedades\/seminarios\/"},"img":{"alt_text":"seminarios-mayo-2022","src":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2022\/05\/seminarios-de-marzo-de-2022-1.png","width":350,"height":200,"srcset":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2022\/05\/seminarios-de-marzo-de-2022-1.png 1x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2022\/05\/seminarios-de-marzo-de-2022-1.png 1.5x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2022\/05\/seminarios-de-marzo-de-2022-1.png 2x"},"classes":[]},{"id":14048,"url":"https:\/\/agorastur.es\/blog\/seminarios-de-abril-2025\/","url_meta":{"origin":14085,"position":2},"title":"Seminarios de abril 2025","author":"\u00e1gorAstur Formaci\u00f3n","date":"01\/04\/2025","format":false,"excerpt":"\ud83c\udf38 Abril: Mes de renovaci\u00f3n, crecimiento y nuevos desaf\u00edos Abril llega con una brisa fresca de oportunidades, y con \u00e9l, nuestra propuesta de seminarios gratuitos para seguir impulsando tu desarrollo. Este mes, nos centramos en reforzar tus habilidades y abrir nuevas puertas para que sigas avanzando en tu camino profesional.\u2026","rel":"","context":"En \u00abSeminarios\u00bb","block_context":{"text":"Seminarios","link":"https:\/\/agorastur.es\/blog\/novedades\/seminarios\/"},"img":{"alt_text":"","src":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/04\/portada-seminarios-abril-2025.jpg","width":350,"height":200,"srcset":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/04\/portada-seminarios-abril-2025.jpg 1x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/04\/portada-seminarios-abril-2025.jpg 1.5x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/04\/portada-seminarios-abril-2025.jpg 2x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/04\/portada-seminarios-abril-2025.jpg 3x"},"classes":[]},{"id":3743,"url":"https:\/\/agorastur.es\/blog\/seminarios-de-mayo-del-2021\/","url_meta":{"origin":14085,"position":3},"title":"Seminarios de mayo del 2021","author":"\u00e1gorAstur Formaci\u00f3n","date":"03\/05\/2021","format":false,"excerpt":"Damos comienzo el mes de mayo con el calendario de los nuevos seminarios de \u00e1gorAstur Formaci\u00f3n. Durante es mes se llevar\u00e1n a cabo todos online, excepto \"manipulador de alimentos\" y \"primeros auxilios\" que se impartir\u00e1n en las delegaciones de Oviedo y Le\u00f3n respectivamente. \u00bfTe apuntas a alguno?\u00a0","rel":"","context":"En \u00abSeminarios\u00bb","block_context":{"text":"Seminarios","link":"https:\/\/agorastur.es\/blog\/novedades\/seminarios\/"},"img":{"alt_text":"","src":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2021\/05\/imagen-seminarios-agorastur.png","width":350,"height":200,"srcset":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2021\/05\/imagen-seminarios-agorastur.png 1x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2021\/05\/imagen-seminarios-agorastur.png 1.5x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2021\/05\/imagen-seminarios-agorastur.png 2x"},"classes":[]},{"id":4163,"url":"https:\/\/agorastur.es\/blog\/seminarios-de-abril-2023\/","url_meta":{"origin":14085,"position":4},"title":"Seminarios de Abril 2023","author":"\u00e1gorAstur Formaci\u00f3n","date":"31\/03\/2023","format":false,"excerpt":"\u00a1Hola a tod@s! Ya est\u00e1n aqu\u00ed los seminarios correspondientes a este mes de abril. \u00bfTe gustar\u00eda desarrollar tus conocimientos sobre inform\u00e1tica? \ud83d\udcbb \u00bfO tal vez siempre quisiste entender mejor las matem\u00e1ticas? \ud83e\uddee \u00bfQuieres aprender sobre anatom\u00eda o primeros auxilios para estar preparado para cualquier situaci\u00f3n? \ud83e\ude7a\ud83d\ude91 Entonces tenemos algo para\u2026","rel":"","context":"En \u00abSeminarios\u00bb","block_context":{"text":"Seminarios","link":"https:\/\/agorastur.es\/blog\/novedades\/seminarios\/"},"img":{"alt_text":"seminarios abril 2023","src":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2023\/03\/Blog800-\u00d7-550-px.png","width":350,"height":200,"srcset":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2023\/03\/Blog800-\u00d7-550-px.png 1x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2023\/03\/Blog800-\u00d7-550-px.png 1.5x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2023\/03\/Blog800-\u00d7-550-px.png 2x"},"classes":[]},{"id":4239,"url":"https:\/\/agorastur.es\/blog\/seminarios-octubre-2023\/","url_meta":{"origin":14085,"position":5},"title":"Seminarios de Octubre 2023","author":"\u00e1gorAstur Formaci\u00f3n","date":"02\/10\/2023","format":false,"excerpt":"Comienza el curso 2023\/2023 y con \u00e9l, el inicio de nuestros seminarios para el nuevo curso en Agorastur Formaci\u00f3n. \ud83d\udcbc\ud83c\udf93 Este mes, traemos una amplia gama de seminarios que abarca desde preparaci\u00f3n de oposiciones a clases de ofim\u00e1tica, \u00a1estamos seguros de que encontrar\u00e1s algo que se ajuste a tus intereses\u2026","rel":"","context":"En \u00abSeminarios\u00bb","block_context":{"text":"Seminarios","link":"https:\/\/agorastur.es\/blog\/novedades\/seminarios\/"},"img":{"alt_text":"","src":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2023\/10\/Blog800-\u00d7-550-px.webp","width":350,"height":200,"srcset":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2023\/10\/Blog800-\u00d7-550-px.webp 1x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2023\/10\/Blog800-\u00d7-550-px.webp 1.5x, https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2023\/10\/Blog800-\u00d7-550-px.webp 2x"},"classes":[]}],"authors":[{"term_id":259,"user_id":1,"is_guest":0,"slug":"agorastur","display_name":"\u00e1gorAstur Formaci\u00f3n","avatar_url":"https:\/\/agorastur.es\/blog\/wp-content\/uploads\/2025\/03\/cropped-favicon-1-96x96.png","1":"","2":"","3":"","4":"","5":"","6":"","7":"","8":""}],"_links":{"self":[{"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/posts\/14085","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/comments?post=14085"}],"version-history":[{"count":1,"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/posts\/14085\/revisions"}],"predecessor-version":[{"id":14088,"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/posts\/14085\/revisions\/14088"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/media\/14086"}],"wp:attachment":[{"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/media?parent=14085"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/categories?post=14085"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/tags?post=14085"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/agorastur.es\/blog\/wp-json\/wp\/v2\/ppma_author?post=14085"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}